{"id":8959,"date":"2024-01-10T15:55:14","date_gmt":"2024-01-10T15:55:14","guid":{"rendered":"https:\/\/daivings.lv\/?p=8959"},"modified":"2026-05-22T05:38:07","modified_gmt":"2026-05-22T05:38:07","slug":"stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps","status":"publish","type":"post","link":"https:\/\/daivings.lv\/de\/die-geschichte-der-udenslides-vor-100-jahren-neptuns-diener\/","title":{"rendered":"Vor 100 Jahren \u201eDiener des Neptun\u201c 42, 43"},"content":{"rendered":"<h3>An einem windigen und sonnigen Tag ist der Geist gl\u00fccklicher<\/h3>\n<p>Dann laufe ich wie ein Fohlen am Strand entlang und springe in die Wellen, um mit ihnen Spa\u00df zu haben. Ich bin genau einundzwanzig Jahre alt und der Lebenswille g\u00e4rt \u00fcber den Rand wie frischer Sauerkrautsaft in einem vollen Fass unter Last. Manchmal tragen wir zusammen mit Vili Paddel, klettern auf K\u00e4ngurus und lesen zwischen der Vergangenheit und der Zukunft von Purciems und essen eine Handvoll Himbeeren und Blaubeeren, w\u00e4hrend unser Mund rot oder blau wird. Bis Mitte August wurden die Schienen gehoben, gez\u00e4hlt und nach Riga gebracht. F\u00fcnf oder sechs fehlen. Ich kann sie nicht finden, genau wie die beiden ertrunkenen Matrosen. \u00dcber solche Kleinigkeiten macht sich niemand Sorgen. Die M\u00f6we selbst schwimmt nicht auf. Der Vater erz\u00e4hlt dem Kapit\u00e4n der Neptun, dass er versuchen wird, sie aus dem schlammigen Meeresboden zu ziehen, indem er den Bug der Neptun als Kran ausbildet.<\/p>\n<p>Das Stahlseil wird in einer vierfachen Drehung umwickelt und ins Wasser gesenkt. Ich seile das Heck der M\u00f6we, weil es nicht gebrochen ist wie der Bug, und Neptun sinkt mit, w\u00e4hrend die Winden an den Seilen ziehen Gesicht nach unten zum Wasser, aber \u2013 die M\u00f6we erhebt sich nicht. Wir warten und geben Kaija Zeit zum Nachdenken. Man h\u00f6rt es unter Wasser knistern und knacken. Schlie\u00dflich kann Kaija es nicht ertragen. Mit einem knackenden Ger\u00e4usch bricht das Heck des Wracks ab und schwimmt mit einem Teil des Decks und dem Steuerrad darauf auf dem Wasser. Neptun stellt alleine ein. Die M\u00f6we steckt viel fester im Lehm als ihr Herrchen. Wir entfernen die Kabine, Mastst\u00e4mme und Pumpen. Wir brechen den Bug des Wracks und heben die Ketten und Anker auf Neptuns Deck hervor. Neptun bringt sie zusammen mit anderen Eisen nach Riga. Wir \u00fcberlassen die zerbrochenen B\u00e4ume den Wellen und Str\u00f6mungen.<\/p>\n<p>Ich gehe noch einmal unter Wasser, um nach den fehlenden Schienen zu suchen. Ich kann es nicht finden. Ich w\u00fcrde im Wrack versinken wie das offene Maul eines Walrosses und angesaugt werden, wie einfach w\u00e4re es jetzt, die Reling anzuheben! Aber es gibt keine Spuren mehr, nur noch mit Schnecken bewachsene Rippen und zerbrochene Bretter, durch deren Ritzen kleine Fische flackern. Sie ern\u00e4hren sich von Algen und Schnecken. Der Seebulle wirft wild seine Stacheln hinter seinen gro\u00dfen Kopf und wedelt mit seinem kleinen Schwanz und schwimmt davon, um ein anderes Zuhause zu suchen.<\/p>\n<p>Auch ich kroch aus dem Wrack auf das Feld, um noch einmal den Meeresboden zu umrunden. Leere Flaschen, Geschirrscherben, Fischgr\u00e4ten, Gurkenschalen und Geschenkpapier zwischen den Fragmenten eines durchn\u00e4ssten Baumes und Algenklumpen zeigen, wie stark wir den Meeresboden verunreinigt haben. Mein erster Knoten wurde von Neptun ins Feld gebracht, komplett mit Deck und Wanten. Keine M\u00fche mehr, es zu l\u00f6sen. Nachdem ich das \u00fcbliche Signal gegeben habe, schaue ich immer noch nach unten, w\u00e4hrend ich nach oben rutsche. Das offene Wrack der Seagull verschwindet unter mir im Halbdunkel in einem gr\u00fcnlich-grauen Nebel. Ich wei\u00df, dass ich nicht noch einmal dorthin zur\u00fcckkehren werde. Die Zukunft wird zeigen, ob tiefe Romantik, Ertrinken und Schiffbr\u00fcche woanders zu finden sein werden.<\/p>\n<p>Wir warten auf Neptun, wir stapeln unsere Sachen. Ich fahre nach Riga und hoffe, neue Hosen zu bekommen. Ich habe es! Nach meiner R\u00fcckkehr nach Riga versuchte ich, die Geschichte von Kaija zu vergessen, denn au\u00dfer b\u00f6sen Tr\u00e4umen und neuen Hosen bekam ich nichts anderes. Ich wollte dem alten Eisen, den Schiffswracks und der F\u00fcrsorge meines Vaters entfliehen. Aber \u2013 am 25. September zog ich das gleiche reparierte Purciem-Outfit noch einmal an, um die gesprengten Eisen auf dem Feld in der N\u00e4he der St\u00fctzen der Rigaer Br\u00fccke in der Daugava anzuheben.<\/p>\n<p>Die Arbeit ist ganz einfach: Man muss die im Schlamm steckenden Eisen ertasten, daran kratzen und warten, bis der Kran sie aus dem Wasser hebt. Das einzige Ungl\u00fcck war das alte Outfit, das schneller auseinanderfiel, als ich es reparieren konnte. Stillstand nichts, das Wasser sammelt sich im Anzug nur um die Beine, aber als man einige Eisen aus dem Schlamm herausholte, musste man sich hinlegen, dann floss das Wasser \u00fcber die Brust, in den Helm und in den Mund. Man k\u00f6nnte es ausspucken, aber wie lange h\u00e4lt es im Wasser? Ich habe meinen Job nach einer Woche gek\u00fcndigt.<\/p>\n<p>In meinen Notizen habe ich folgende Szene dargestellt: Der Nordwestwind treibt die gr\u00fcnen Meereswellen hinauf und vermischt das br\u00e4unliche Wasser der Daugava zu grauer Tr\u00fcbung, wodurch wei\u00dfe Schaumstreifen auf der Oberfl\u00e4che entstehen. Sein Licht kann nur ein bis zwei Meter ins Wasser eindringen, aber in einer Tiefe von zehn Metern herrscht selbst an einem sonnigen Tag Nacht. F\u00fc\u00dfe versinken im Schlamm und verheddern sich in Stacheldrahtgeflechten. Wie ein Blinder streckt man die Arme nach vorn und tastet nach der St\u00fctze der Br\u00fccke, die scheinbar direkt \u00fcber dem Kopf aufragt, in Wirklichkeit aber mehrere Meter entfernt ist. Um die St\u00fctze herum hat der Bach eine tiefe Grube ausgerissen. Dort liegen Stacheldr\u00e4hte, Pfahlenden, Splitter, von der Str\u00f6mung mitgerissene, verzweigte B\u00e4ume in Stapeln \u00fcber den Eisen der gesprengten Br\u00fccke.<\/p>\n<p>Sie m\u00fcssen Ihrer Fantasie nur ein wenig freien Lauf lassen, um das Gef\u00fchl zu haben, auf einem sumpfigen Schlachtfeld zur\u00fcckgelassen worden zu sein. Je h\u00f6her man an der S\u00e4ule entlang geht, desto heller wird es. Schatten gleiten schnell \u00fcber den Tr\u00e4ger, verschwinden bald und verdichten sich bald wieder in den grellsten Formen. Ein Mystiker w\u00fcrde sagen: die Seelen der im Krieg Gefallenen, ein Dichter \u2013 das Spiel tosender Wellen, und ein Taucher w\u00fcrde ausspucken. Es macht viel mehr Spa\u00df, wenn man wieder sieht, wie hoch der Schaum der Daugava ist und wie schnell die Wolken dar\u00fcber ziehen.\u201c Ich \u00fcberlie\u00df die Eisen den Schatten, um weiter zu lernen und Unterricht in Mathematik, Chemie und Physik f\u00fcr einen Lat pro Stunde zu geben. Zumindest in der Trockenzeit kann man an die Zukunft denken.<\/p>\n<p>Vater hatte bereits dar\u00fcber nachgedacht und mich gerufen, um beim Abriss des ber\u00fchmten Nordpol-Expeditionsschiffs Nordschild zu helfen. Ich musste nicht zum Nordpol, da Nordschild direkt hinter den Daugava-Anlegestellen zu Wasser gelassen wurde. Im Februar und M\u00e4rz haben wir auf die gleiche Weise von oben gearbeitet und ein Loch in das Eis geschnitten. Der Nordschild war stark gebaut \u2013 aus Holz mit Eisenstangen und Platten, noch nicht von Wellen und Eis zerschmettert. Vater wollte den Kessel und die Maschine des Dampfers, vor allem aber die Kupfer- und Bleirohre, die durch die Eingeweide des Schiffes f\u00fchrten. Im Winter war das Wasser sehr klar, da die Eisklippen am dritten Ufer Nordschild vor Wellen und Str\u00f6mungen sch\u00fctzten.<\/p>\n<p>Als man sich \u00fcber die Abalone beugte, konnte man auch von oben einige R\u00f6hren sehen und einhaken. Wir holten sie mit einer Handwinde aus dem Wasser und \u2013 unsere Kopeke kam heraus und verkaufte sie an einen Juden. Wir haben einen kleinen Windschutz gebaut, aber im M\u00e4rz gab es so warme und sonnige Tage, dass ich w\u00e4hrend der Arbeit sogar mein Hemd ausziehen und viel Sonne bekommen konnte. Vater hat es auch versucht, aber er hatte Sommersprossen auf dem R\u00fccken, die nie verschwanden. Sonne auf Eis ist \u00e4tzend. Aprilwinde trieben uns vom Eis. Um Wilni zu retten, musste man sich beeilen. Als Vaters Freund am Bau einer Pontonbr\u00fccke arbeitete, kenterte sein Schlepper Vilnis in der Str\u00f6mung und sank. Ein Freund beschwerte sich, dass kein Taucher in einem solchen Bach tauchen m\u00f6chte, aber sein Vater beruhigte ihn: \u201eMein Junge wird es tun!\u201c<\/p>\n<h3>Zumindest h\u00e4tte er mich gefragt, ob ich in so einem Bach regnen wollte!<\/h3>\n<p>Aber es war notwendig zu gie\u00dfen. Ich habe die Ger\u00e4te und Assistenten sehr gut verstanden. Ich band schwere Ketten um die Stiefel, damit sie nicht auftrieben, und in der N\u00e4he von Vilnius lie\u00dfen sie ein schweres Ankerseil auf den Grund des Flusses Daugava herab, mit dem man hinunterklettern konnte. Allerdings hielten die H\u00e4nde nicht lange. Die Str\u00f6mung zog mich vom Seil und warf mich wie einen Korken hinaus. Ich klammerte mich am Seil fest und versuchte mich loszurei\u00dfen, aber das Signalseil und der Schlauch hielten mich fest. Ich wickelte weitere Ketten um meine Beine und um meinen Bauch, und schlie\u00dflich kam ich hinunter, wo die vom Kran zum Schlepper herabgelassenen Kabel auf mich warteten. Ich wurde noch ein paar Mal auf das Feld geworfen, w\u00e4hrend es gelang, die Seile am Schlepper festzubinden und richtig zu fesseln. Ich k\u00e4mpfte f\u00fcnf Stunden lang mit der Str\u00f6mung und den Seilen, wof\u00fcr mein Vater achtzig Lats erhielt, und wir wurden beide in einem Restaurant mit W\u00fcrstchen und Sauerkraut verw\u00f6hnt.<\/p>\n<p>Die Br\u00fccke und Daugavmala sollen voller Zuschauer gewesen sein. Ich habe es neulich auch in den Zeitungen gesehen, wo auch ein Taucher fotografiert wurde, der auf einer Leiter stand und in der Str\u00f6mung schwamm, und der Kran war auch dabei, einen Schlepper mit Kabeln aufzubauen. In einer langen Beschreibung wurde der Hafentaucher gelobt und ein wenig besungen. Ich hatte einen Hafentaucheranzug benutzt und niemand schaute hinein, was sich darin befand. Ebenso dringend war es, das gesunkene Kohleboot bei Vollers zu heben, das Segel Ansis zu reparieren und das Segel Anna an Land zu ziehen.<\/p>\n<p>Ich hatte keine Zeit zum Ausruhen, als wir wieder bei Nordschild hinter Daugavgriva waren. Es begann eine eint\u00f6nige Arbeit mit geringem Gewinn und einigen Komplikationen, die sich gleichzeitig verschlimmerten. Wir hoben den Kessel mit einem kleinen Schwimmkran an, der, w\u00e4hrend der Kessel an den Seilen hing, so tief sank, dass er nicht \u00fcber die B\u00e4nke reichte. Man musste auf die Stufe steigen: die Last auf den Boden legen, einen Schritt zur\u00fccktreten und den Topf wieder n\u00e4her heranziehen. Der Kran konnte es nicht ertragen, an den Ufern der Kessel entlang zu fahren. Der Kessel warf ihn auf die Seite, zerbrach die St\u00fctzen und sank im Hafen. Die Bretter flogen durch die Luft und mit ihnen ein Mann, der es nicht rechtzeitig bemerkte, zur Seite zu springen. Der Flug endete gl\u00fccklich nur im Schwimmen. Wir haben den Kessel sp\u00e4ter mit einem gr\u00f6\u00dferen Kran angehoben, und dort floss der potenzielle Gewinn.<\/p>\n<p>In der N\u00e4he zogen Fischer Leinen und baten mich um Hilfe, wenn die Leinen an einem Fang h\u00e4ngen blieben. Dann k\u00f6nnte ich meiner Mutter einen Eimer oder einen Eimer mit kleineren Fischen bringen. Es wurde geh\u00f6rt, dass ein Seemann, der die sieben Weltmeere bereist hatte, mit dem Mund in einer Sch\u00fcssel ertrank. Ein Taucher kann auch \u201ein einer Mundschale ertrinken\u201c, wenn er nicht aufpasst. Ich hatte Probleme bei Nordschild, wo das Wasser, wie man sagt, nicht tiefer ist als der Bauch einer Ente. Wie es dazu kam, habe ich in meinen Notizen beschrieben: \u201eAm Samstagmorgen hatten wir vor, das Schiffsdeck \u00fcber den Maschinenr\u00e4umen zu sprengen, um an die Dampfmaschine zu gelangen. Ich habe eine starke Ladung angelegt. Das Deck brach auseinander, aber die Explosion riss auch ein Loch in die Seite des Schiffes. Damit begann der flie\u00dfende Sand des Meeres in die Maschinenr\u00e4ume zu str\u00f6men, der das gesamte Wrack zu f\u00fcllen drohte. Ich verbarrikadierte das gestanzte Loch mit Blechst\u00fccken und beeilte mich, das Auto in die Luft zu jagen. Ich befestigte einen TNT-Stein an jedem Bein des Autos und lie\u00df es fliegen. Aber das Auto f\u00e4hrt nicht in der Luft! Wenn ich es im Dunkeln ber\u00fchre, steht es wie auf allen Vieren. Der aus der W\u00e4scherei, wenn ich daran vorbeigehe. Das Bein mit einem Teil des Rumpfes erfasst meine linke Schulter und dr\u00fcckt sie gegen die Wand. Ich lege mich hin und bewege mich nicht, weil ich Angst habe, dass ein Teil meines Oberk\u00f6rpers am Helm h\u00e4ngen bleiben k\u00f6nnte. Bei Gusseisen wei\u00df man nie. Ich m\u00f6chte meinen Zustand herausfinden, aber wie kann ich das tun, wenn das Wasser so dick ist? M\u00f6glicherweise m\u00fcssen Sie bis zum Weltuntergang warten, bis das Wasser klar wird. Durch das Loch in der Seite des Schiffes kann ich h\u00f6ren, wie der Sand am Helm vorbeil\u00e4uft. Es wird nicht mehr lange dauern, bis ich begraben bin.<\/p>\n<p>Au\u00dferdem gelangt wenig Luft in den Helm, da der Schlauch unter dem Gusseisenblock komprimiert wird. Zusammen mit dem Signalseil blieb es auf der anderen Seite des Beins. Ich versuche mich zu bewegen. Meine Beine und meine rechte Hand bewegen sich, aber meine linke Hand steckt im Schlamm fest, der den Aufprall wie ein weiches Kissen ausgehalten hat. Wie kann man den Luftschlauch l\u00f6sen und auf die Seite legen? Ich erinnere mich, dass ich ein Brecheisen in die N\u00e4he meiner rechten Hand gelegt habe, das ich nicht erreichen kann. Ich tappe durch den Schlamm, bis ich den Eisendraht sp\u00fcre. Ich bog ein Ende zu einem Haken zusammen und fing an, nach der Rute zu fischen. Ich finde es, aber es ist schwer, ihm n\u00e4her zu kommen. Der Drahthaken gleitet entlang des glatten Eisens. Ich muss es in eine Spirale schneiden, damit es sich irgendwie um den Stab wickelt. Besorgt beginnt der Vater, am Signalseil zu ziehen. Mit demselben Drahthaken ist es m\u00f6glich, das Seil zu ertasten und einmal daran zu ziehen.<\/p>\n<p>Es ist ein Zeichen daf\u00fcr, dass es mir gut geht, also lass es ruhig angehen. Er wird anfangen zu ziehen und Gusseisen auf mich legen! Ich bin verschwitzt und tue fast nichts, aber endlich halte ich den Riegel in der Hand. Ich ber\u00fchre den Schlauch mit seinem Ende und dr\u00fccke ihn nach unten. Der Schlauch wird freigegeben und es ist wieder gen\u00fcgend Luft vorhanden! W\u00e4hrend ich Luft trinke, stiche ich mit einer Rute in das Bein des Autos und den Boden des Wracks, um zu wissen, was als n\u00e4chstes zu tun ist. Es stellte sich heraus, dass das Bein des Autos direkt \u00fcber meinem Kopf gegen die Schiffswand prallte und eine L\u00fccke in der Kurve des Wracks hinterlie\u00df, aus der ich herauskommen k\u00f6nnte, wenn es keine Angst und keinen Schlamm g\u00e4be. Ich bin schon halb im Sand und muss schnell handeln. Ich versuche, den Schlamm abzukratzen, um meine linke Hand zu befreien, ich drehe meinen K\u00f6rper in die St\u00fctze des Autos und bewege mich mit H\u00e4nden und F\u00fc\u00dfen vorw\u00e4rts, wobei ich den Schlamm in meinen H\u00e4nden aufr\u00fchre. Ich habe den Helm und die Schultern durch, ich komme nicht weiter. Die Leinen stecken fest und lassen mich weder vorw\u00e4rts noch r\u00fcckw\u00e4rts gehen.<\/p>\n<p>Ich schlafe und denke, dass f\u00fcr den Abend ein Date vereinbart wurde, aber ich wei\u00df nicht mehr mit wem: Isolde, Valentina, Erika oder jemand anders. Es spielt keine Rolle, mit wem und was verhandelt wurde, aber Sie m\u00fcssen rausgehen und Ihr Versprechen einl\u00f6sen. Der Sand denkt nicht, er flie\u00dft nur in einem Strom, und meine F\u00fc\u00dfe sind schon tief darunter. ~Eureka!\u201c \u2013 Etwas kam mir in den Sinn: Wenn ich jetzt diese St\u00fctze nehmen w\u00fcrde, w\u00fcrde mir das Bein des Autos nicht brechen! Ich dr\u00fccke beide H\u00e4nde gegen die Enden der Pfeile: Die St\u00fctze bewegt sich, aber sie schwingt zur\u00fcck. Na und? \u2013 Ich wickle das Signalseil um die Pfeile und gebe das Signal \u2013 zum Ziehen! Das Seil dehnt sich, auch ich dr\u00fccke so stark ich kann, das Bein schlingt sich um meins, ohne es zu ber\u00fchren, und \u2013 ich bin gerettet! Als er aus dem Friedhof des Schiffes kam, das genau dort war oder auch mir geh\u00f6rte, warf er seine Kleider ab und war \u00fcberrascht zu sehen, dass die Sonne sich bereits darauf vorbereitete, im Meer zu schlafen. Ich kann am Gesicht meines Vaters erkennen, dass es f\u00fcr ihn schwerer war, nichts zu tun, als f\u00fcr mich, im Schlamm zu suhlen. Ich gehe nicht mehr auf ein Date, aber ich werde es dir verzeihen, wenn ich es dir morgen sage. \u2014 Vater versteht, ohne es zu sagen. Der Junge ist wieder wach. Was mehr? Wir haben es kaum geschafft, das gesprengte Gusseisen herauszuheben, als das Wrack bereits vollst\u00e4ndig im Sand versunken ist und wir im ber\u00fchmten Nordpolreiter nichts mehr zu suchen haben.<\/p>","protected":false},"excerpt":{"rendered":"<p>An einem windigen und sonnigen Tag ist der Geist gl\u00fccklicher. Dann renne ich wie ein Fohlen am Strand und springe in die Wellen, um mit ihnen Spa\u00df zu haben. Ich bin genau einundzwanzig Jahre alt und der Lebenswille g\u00e4rt \u00fcber den Rand wie frischer Sauerkrautsaft in einem vollen Fass unter Last. Manchmal [\u2026]<\/p>","protected":false},"author":166,"featured_media":8960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1591],"tags":[],"class_list":["post-8959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kugu-vraki"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pirms 100.gadiem &quot;Nept\u016bna kalps&quot; 42, 43 - Daivings.lv<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/daivings.lv\/de\/die-geschichte-der-udenslides-vor-100-jahren-neptuns-diener\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pirms 100.gadiem &quot;Nept\u016bna kalps&quot; 42, 43 - Daivings.lv\" \/>\n<meta property=\"og:description\" content=\"V\u0113jain\u0101 un saulain\u0101 dien\u0101 pr\u0101ts ir priec\u012bg\u0101ks Tad skraidu k\u0101 kume\u013c\u0161 pa pludmali un lecu vi\u013c\u0146os ar tiem patrakoties. Man ir taisni divdesmit viens gads, un dz\u012bvotgriba r\u016bgst p\u0101ri malai k\u0101 svaigi sk\u0101b\u0113tu k\u0101postu sula piln\u0101 muc\u0101 zem sloga. Reiz\u0113m [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/daivings.lv\/de\/die-geschichte-der-udenslides-vor-100-jahren-neptuns-diener\/\" \/>\n<meta property=\"og:site_name\" content=\"Daivings.lv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/daivings\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-10T15:55:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-22T05:38:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/daivings.lv\/wp-content\/uploads\/Neptuna-kalps.png?v=1706274847\" \/>\n\t<meta property=\"og:image:width\" content=\"1232\" \/>\n\t<meta property=\"og:image:height\" content=\"928\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Dr. Krasti\u0146\u0161 K\u0101rlis\u00a0\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@daivings\" \/>\n<meta name=\"twitter:site\" content=\"@daivings\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Krasti\u0146\u0161 K\u0101rlis\u00a0\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\\\/\"},\"author\":{\"name\":\"Dr. Krasti\u0146\u0161 K\u0101rlis\u00a0\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/person\\\/4d8b17b4f91c344d622d598303a333f3\"},\"headline\":\"Pirms 100.gadiem &#8220;Nept\u016bna kalps&#8221; 42, 43\",\"datePublished\":\"2024-01-10T15:55:14+00:00\",\"dateModified\":\"2026-05-22T05:38:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\\\/\"},\"wordCount\":2601,\"publisher\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/Neptuna-kalps.png?v=1706274847\",\"articleSection\":[\"Ku\u0123u vraki\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\\\/\",\"url\":\"https:\\\/\\\/daivings.lv\\\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\\\/\",\"name\":\"Pirms 100.gadiem \\\"Nept\u016bna kalps\\\" 42, 43 - Daivings.lv\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/Neptuna-kalps.png?v=1706274847\",\"datePublished\":\"2024-01-10T15:55:14+00:00\",\"dateModified\":\"2026-05-22T05:38:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/daivings.lv\\\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/Neptuna-kalps.png?v=1706274847\",\"contentUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/Neptuna-kalps.png?v=1706274847\",\"width\":1232,\"height\":928,\"caption\":\"Nept\u016bna kalps\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"S\u0101kums\",\"item\":\"https:\\\/\\\/daivings.lv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pirms 100.gadiem &#8220;Nept\u016bna kalps&#8221; 42, 43\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#website\",\"url\":\"https:\\\/\\\/daivings.lv\\\/\",\"name\":\"Daivings.lv\",\"description\":\"PADI kursi Latvij\u0101, Daivinga klubs pied\u0101v\u0101 nir\u0161anas kursus &amp; PADI Instruktors\",\"publisher\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/daivings.lv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#organization\",\"name\":\"Daivings.lv\",\"url\":\"https:\\\/\\\/daivings.lv\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_recolor.png\",\"contentUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_recolor.png\",\"width\":268,\"height\":70,\"caption\":\"Daivings.lv\"},\"image\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/daivings\\\/\",\"https:\\\/\\\/x.com\\\/daivings\",\"https:\\\/\\\/instagram.com\\\/daivingslv\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/person\\\/4d8b17b4f91c344d622d598303a333f3\",\"name\":\"Dr. Krasti\u0146\u0161 K\u0101rlis\u00a0\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5eb1e14f8a386da511fd4f75f9de8ebb10fca219b15df064de68ec18da28f828?s=96&d=wavatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5eb1e14f8a386da511fd4f75f9de8ebb10fca219b15df064de68ec18da28f828?s=96&d=wavatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5eb1e14f8a386da511fd4f75f9de8ebb10fca219b15df064de68ec18da28f828?s=96&d=wavatar&r=g\",\"caption\":\"Dr. Krasti\u0146\u0161 K\u0101rlis\u00a0\"},\"url\":\"https:\\\/\\\/daivings.lv\\\/de\\\/author\\\/krastinskarlis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vor 100 Jahren \u201eDiener des Neptun\u201c 42, 43 - Daivings.lv","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/daivings.lv\/de\/die-geschichte-der-udenslides-vor-100-jahren-neptuns-diener\/","og_locale":"de_DE","og_type":"article","og_title":"Pirms 100.gadiem \"Nept\u016bna kalps\" 42, 43 - Daivings.lv","og_description":"V\u0113jain\u0101 un saulain\u0101 dien\u0101 pr\u0101ts ir priec\u012bg\u0101ks Tad skraidu k\u0101 kume\u013c\u0161 pa pludmali un lecu vi\u013c\u0146os ar tiem patrakoties. Man ir taisni divdesmit viens gads, un dz\u012bvotgriba r\u016bgst p\u0101ri malai k\u0101 svaigi sk\u0101b\u0113tu k\u0101postu sula piln\u0101 muc\u0101 zem sloga. Reiz\u0113m [&hellip;]","og_url":"https:\/\/daivings.lv\/de\/die-geschichte-der-udenslides-vor-100-jahren-neptuns-diener\/","og_site_name":"Daivings.lv","article_publisher":"https:\/\/facebook.com\/daivings\/","article_published_time":"2024-01-10T15:55:14+00:00","article_modified_time":"2026-05-22T05:38:07+00:00","og_image":[{"width":1232,"height":928,"url":"https:\/\/daivings.lv\/wp-content\/uploads\/Neptuna-kalps.png?v=1706274847","type":"image\/png"}],"author":"Dr. Krasti\u0146\u0161 K\u0101rlis\u00a0","twitter_card":"summary_large_image","twitter_creator":"@daivings","twitter_site":"@daivings","twitter_misc":{"Verfasst von":"Dr. Krasti\u0146\u0161 K\u0101rlis\u00a0","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/daivings.lv\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\/#article","isPartOf":{"@id":"https:\/\/daivings.lv\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\/"},"author":{"name":"Dr. Krasti\u0146\u0161 K\u0101rlis\u00a0","@id":"https:\/\/daivings.lv\/#\/schema\/person\/4d8b17b4f91c344d622d598303a333f3"},"headline":"Pirms 100.gadiem &#8220;Nept\u016bna kalps&#8221; 42, 43","datePublished":"2024-01-10T15:55:14+00:00","dateModified":"2026-05-22T05:38:07+00:00","mainEntityOfPage":{"@id":"https:\/\/daivings.lv\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\/"},"wordCount":2601,"publisher":{"@id":"https:\/\/daivings.lv\/#organization"},"image":{"@id":"https:\/\/daivings.lv\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\/#primaryimage"},"thumbnailUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/Neptuna-kalps.png?v=1706274847","articleSection":["Ku\u0123u vraki"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/daivings.lv\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\/","url":"https:\/\/daivings.lv\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\/","name":"Vor 100 Jahren \u201eDiener des Neptun\u201c 42, 43 - Daivings.lv","isPartOf":{"@id":"https:\/\/daivings.lv\/#website"},"primaryImageOfPage":{"@id":"https:\/\/daivings.lv\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\/#primaryimage"},"image":{"@id":"https:\/\/daivings.lv\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\/#primaryimage"},"thumbnailUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/Neptuna-kalps.png?v=1706274847","datePublished":"2024-01-10T15:55:14+00:00","dateModified":"2026-05-22T05:38:07+00:00","breadcrumb":{"@id":"https:\/\/daivings.lv\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/daivings.lv\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/daivings.lv\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\/#primaryimage","url":"https:\/\/daivings.lv\/wp-content\/uploads\/Neptuna-kalps.png?v=1706274847","contentUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/Neptuna-kalps.png?v=1706274847","width":1232,"height":928,"caption":"Nept\u016bna kalps"},{"@type":"BreadcrumbList","@id":"https:\/\/daivings.lv\/stasts-par-udenslidejiem-pirms-100-gadiem-neptuna-kalps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"S\u0101kums","item":"https:\/\/daivings.lv\/"},{"@type":"ListItem","position":2,"name":"Pirms 100.gadiem &#8220;Nept\u016bna kalps&#8221; 42, 43"}]},{"@type":"WebSite","@id":"https:\/\/daivings.lv\/#website","url":"https:\/\/daivings.lv\/","name":"Tauchen.lv","description":"PADI-Kurse in Lettland, Tauchclub bietet Tauchkurse und PADI-Lehrer an","publisher":{"@id":"https:\/\/daivings.lv\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/daivings.lv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/daivings.lv\/#organization","name":"Tauchen.lv","url":"https:\/\/daivings.lv\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/daivings.lv\/#\/schema\/logo\/image\/","url":"https:\/\/daivings.lv\/wp-content\/uploads\/2024\/01\/Logo_recolor.png","contentUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/2024\/01\/Logo_recolor.png","width":268,"height":70,"caption":"Daivings.lv"},"image":{"@id":"https:\/\/daivings.lv\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/daivings\/","https:\/\/x.com\/daivings","https:\/\/instagram.com\/daivingslv\/"]},{"@type":"Person","@id":"https:\/\/daivings.lv\/#\/schema\/person\/4d8b17b4f91c344d622d598303a333f3","name":"DR. Krastins K\u0101rlis\u00a0","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5eb1e14f8a386da511fd4f75f9de8ebb10fca219b15df064de68ec18da28f828?s=96&d=wavatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5eb1e14f8a386da511fd4f75f9de8ebb10fca219b15df064de68ec18da28f828?s=96&d=wavatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb1e14f8a386da511fd4f75f9de8ebb10fca219b15df064de68ec18da28f828?s=96&d=wavatar&r=g","caption":"Dr. Krasti\u0146\u0161 K\u0101rlis\u00a0"},"url":"https:\/\/daivings.lv\/de\/author\/krastinskarlis\/"}]}},"_links":{"self":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/posts\/8959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/users\/166"}],"replies":[{"embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/comments?post=8959"}],"version-history":[{"count":0,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/posts\/8959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/media\/8960"}],"wp:attachment":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/media?parent=8959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/categories?post=8959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/tags?post=8959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}