{"id":8930,"date":"2024-01-04T11:18:38","date_gmt":"2024-01-04T11:18:38","guid":{"rendered":"https:\/\/daivings.lv\/?p=8930"},"modified":"2024-01-04T11:36:37","modified_gmt":"2024-01-04T11:36:37","slug":"cik-dzili-varat-nirt-ar-akvalangu","status":"publish","type":"post","link":"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/","title":{"rendered":"Wie tief kann man tauchen?"},"content":{"rendered":"<p>Tauchen, eine k\u00f6rperlich aktive, adrenalingeladene und aufregende Aktivit\u00e4t, die uns Zugang zu einem au\u00dfergew\u00f6hnlichen Unterwasserreich verschafft, wirft bei Anf\u00e4ngern und Tauchern oft die Frage auf: \u201eWie tief k\u00f6nnen wir gehen?\u201c In diesem Artikel werden wir gemeinsam mit den Tauchlehrern des Unterwassertauchclubs \u201eDaivings\u201c nach Antworten suchen und uns mit dem Bereich der Tiefenbeschr\u00e4nkungen befassen und erfahren, was eine sichere und verantwortungsvolle Aus\u00fcbung des Tauchens ausmacht Tauchen.<\/p>\n<figure id=\"attachment_8537\" aria-describedby=\"caption-attachment-8537\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/daivings.lv\/ko-darit-udenslidejam-zem-udens-nirsanas-laika-ja-gribas-urinet\/daivinga-eksperta-valtera-preimana-padoms-9-2\/\" rel=\"attachment wp-att-8537\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8537\" src=\"https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-9-1-300x225.jpeg\" alt=\"Wie tief kann man tauchen?\" width=\"300\" height=\"225\" srcset=\"https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-9-1-300x225.jpeg?v=1706274987 300w, https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-9-1-1024x768.jpeg?v=1706274987 1024w, https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-9-1-768x576.jpeg?v=1706274987 768w, https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-9-1-1536x1152.jpeg?v=1706274987 1536w, https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-9-1-16x12.jpeg?v=1706274987 16w, https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-9-1-1000x750.jpeg?v=1706274987 1000w, https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-9-1-230x173.jpeg?v=1706274987 230w, https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-9-1-350x263.jpeg?v=1706274987 350w, https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-9-1-480x360.jpeg?v=1706274987 480w, https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-9-1.jpeg?v=1706274987 2016w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-8537\" class=\"wp-caption-text\">Wie tief kann man tauchen?<\/figcaption><\/figure>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Inhaltsverzeichnis ein-\/ausblenden\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Umschalten<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/#Nirsana_atputai_ne_dzilak_ka_40_metri\" >Sporttauchen, nicht tiefer als 40 Meter<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/#Dzilak_par_40_metri_ir_tehniskas_nirsanas_apmaciba_bezbailigajiem\" >Tiefer als 40 Meter ist technisches Tauchtraining f\u00fcr Furchtlose<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/#Sadarbosanas_ar_nirsanas_ekspertiem_uzzinam_noteikumus_dziluma_apmeklejumam\" >In Zusammenarbeit mit Tauchexperten erlernen wir die Regeln f\u00fcr den Besuch der Tiefe<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/#Jautajums_Kadi_faktori_ietekme_nireja_maksimalo_droso_dzilumu\" >Frage: Welche Faktoren beeinflussen die maximale sichere Tiefe eines Tauchers?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/#Jautajums_Vai_es_varu_ienirt_dzilak_trenejoties\" >Frage: Kann ich w\u00e4hrend des Trainings tiefer tauchen?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/#Jautajums_Kadi_ir_raksturigie_riski_kas_saistiti_ar_nirsanu_talak_par_40_metriem\" >Frage: Welche Risiken sind mit dem Tauchen \u00fcber 40 Meter verbunden?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/#Jautajums_Ka_mes_varam_drosi_izpetit_dzilakus_dzilumus_neapdraudot_drosibu\" >Frage: Wie k\u00f6nnen wir tiefere Tiefen sicher erkunden, ohne die Sicherheit zu gef\u00e4hrden?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/#Jautajums_Kadi_ir_etiski_apsverumi_nirstot_ekstremala_dziluma\" >Frage: Welche ethischen \u00dcberlegungen gibt es beim Tauchen in extremen Tiefen?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/#Celojums_dziluma_kopa_ar_zinasanam\" >Eine Reise in die Tiefe, gepaart mit Wissen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/#Patstaviga_nirsanas_prakse_nirstam_dziluma\" >Unabh\u00e4ngige Tauchpraxis, tief tauchen<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Nirsana_atputai_ne_dzilak_ka_40_metri\"><\/span>Sporttauchen, nicht tiefer als 40 Meter<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>F\u00fcr Sporttaucher die erreichbare Tiefengrenze <a href=\"https:\/\/daivings.lv\/deep-diving-specialitate\/\"><strong>PADI-TIEFTAUCHER<\/strong><\/a> betr\u00e4gt in der Regel 40 Meter (130 Fu\u00df). Dieser von renommierten Tauchorganisationen wie PADI, SSI und NAUI sorgf\u00e4ltig entwickelte Standard basiert auf gr\u00fcndlicher wissenschaftlicher Forschung und einem tiefen Verst\u00e4ndnis von Sicherheitsaspekten. Die 40-Meter-Grenze beim Tauchen ergibt sich aus zwei Hauptfaktoren:<\/p>\n<ul>\n<li><a href=\"https:\/\/daivings.lv\/kas-ir-dekompresijas-slimiba-un-kadi-ir-simptomi\/\"><strong>Dekompressionskrankheit (DCS)<\/strong><\/a>: Wenn Taucher aus tieferen Tiefen aufsteigen, f\u00fchrt der verringerte Druck dazu, dass gel\u00f6ster Stickstoff im Blutkreislauf Blasen bildet. Wenn diese Blasen nicht richtig behandelt werden, k\u00f6nnen sie zur Dekompressionskrankheit (DCS) f\u00fchren, einem potenziell schw\u00e4chenden Zustand, der durch Gelenkschmerzen, Hautausschl\u00e4ge und neurologische St\u00f6rungen gekennzeichnet ist.<\/li>\n<li><a href=\"https:\/\/daivings.lv\/slapekla-narkoze-nirsana\/\"><strong>Stickstoffnarkose<\/strong><\/a><a href=\"https:\/\/daivings.lv\/slapekla-narkoze-udenslidejiem\/\"><strong>:<\/strong><\/a> In gr\u00f6\u00dferer Tiefe kann die erh\u00f6hte Stickstoffkonzentration im Blutkreislauf des Tauchers zu einem ver\u00e4nderten Bewusstseinszustand f\u00fchren, der als Stickstoffnarkose bezeichnet wird. Dieser Zustand ist durch eingeschr\u00e4nktes Urteilsverm\u00f6gen, Euphorie und sogar Halluzinationen gekennzeichnet, was die F\u00e4higkeit des Tauchers, fundierte Entscheidungen zu treffen und sichere Tauchpraktiken durchzuf\u00fchren, erheblich beeintr\u00e4chtigt.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Dzilak_par_40_metri_ir_tehniskas_nirsanas_apmaciba_bezbailigajiem\"><\/span>Tiefer als 40 Meter ist technisches Tauchtraining f\u00fcr Furchtlose<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>F\u00fcr diejenigen, die die Grenzen der Tiefenerkundung, tiefer als 40 Meter, erweitern m\u00f6chten, erweist sich das technische Tauchen als eine spezialisierte Tieftauchdisziplin. Technische Taucher absolvieren eine strenge Ausbildung, <a href=\"https:\/\/daivings.lv\/tec-trimix-diver\/\"><em><strong>FLIE\u00df TIEF<\/strong><\/em><\/a> Kurse und nutzt moderne Ausr\u00fcstung, um die Grenzen des Sporttauchens sicher zu \u00fcberschreiten. Sie verwenden spezielle Gasmischungen wie Trimix (Sauerstoff, Helium und Stickstoff), um die Dekompression effektiv zu steuern und die Auswirkungen der Stickstoffnarkose zu reduzieren.<\/p>\n<figure id=\"attachment_8566\" aria-describedby=\"caption-attachment-8566\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/daivings.lv\/daivinga-centrs\/img_3267\/\" rel=\"attachment wp-att-8566\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8566\" src=\"https:\/\/daivings.lv\/wp-content\/uploads\/IMG_3267-300x226.jpg\" alt=\"Valters Preimanis mit Tauchfreunden in \u00c4gypten, Rotes Meer\" width=\"300\" height=\"226\" \/><\/a><figcaption id=\"caption-attachment-8566\" class=\"wp-caption-text\">In \u00c4gypten, am Roten Meer<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Sadarbosanas_ar_nirsanas_ekspertiem_uzzinam_noteikumus_dziluma_apmeklejumam\"><\/span>In Zusammenarbeit mit Tauchexperten erlernen wir die Regeln f\u00fcr den Besuch der Tiefe<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Um die Tiefengrenzen weiter zu kl\u00e4ren, tauchen wir in eine Frage-und-Antwort-Runde mit erfahrenen Tauchprofis des Unterwassertauchclubs \u201eDaivings\u201c ein:<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Jautajums_Kadi_faktori_ietekme_nireja_maksimalo_droso_dzilumu\"><\/span>Frage: Welche Faktoren beeinflussen die maximale sichere Tiefe eines Tauchers?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Neben Ausbildung und Erfahrung spielen auch die individuellen Merkmale eines Tauchers wie Alter, Fitnessniveau und zugrundeliegende Gesundheitszust\u00e4nde eine entscheidende Rolle bei der Bestimmung seiner maximal sicheren Tiefe. Dar\u00fcber hinaus wirken sich auch der jeweilige Tauchplatz, Umweltfaktoren und die Art des Tauchplans auf die Tiefengrenzen aus.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Jautajums_Vai_es_varu_ienirt_dzilak_trenejoties\"><\/span>Frage: Kann ich w\u00e4hrend des Trainings tiefer tauchen?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>W\u00e4hrend zus\u00e4tzliches Training zweifellos die F\u00e4higkeiten und Fertigkeiten eines Tauchers verbessert, bedeutet dies nicht automatisch, dass die Tiefengrenze \u00fcberschritten wird. Fortgeschrittene technische Tauchzertifikate, <a href=\"https:\/\/daivings.lv\/padi-tec-50-diver\/\"><strong>PADI TEC DEEP<\/strong><\/a>, vermittelt das notwendige Wissen und die notwendigen Techniken, um tiefere Tauchg\u00e4nge sicher durchzuf\u00fchren, aber die zugrunde liegenden physiologischen Einschr\u00e4nkungen bleiben bestehen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Jautajums_Kadi_ir_raksturigie_riski_kas_saistiti_ar_nirsanu_talak_par_40_metriem\"><\/span>Frage: Welche Risiken sind mit dem Tauchen \u00fcber 40 Meter verbunden?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Das Risiko einer Dekompressionskrankheit und einer Stickstoffnarkose steigt mit zunehmender Tiefe deutlich an. Dar\u00fcber hinaus erh\u00f6ht die Komplexit\u00e4t der technischen Tauchausr\u00fcstung und -verfahren das Risiko von Fehlern und Komplikationen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Jautajums_Ka_mes_varam_drosi_izpetit_dzilakus_dzilumus_neapdraudot_drosibu\"><\/span>Frage: Wie k\u00f6nnen wir tiefere Tiefen sicher erkunden, ohne die Sicherheit zu gef\u00e4hrden?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ein umfassendes Verst\u00e4ndnis der Tauchumgebung, sorgf\u00e4ltige Planung und die strikte Einhaltung von Sicherheitsprotokollen sind beim Tieftauchen von entscheidender Bedeutung. Technische Tauchkurse vermitteln Tauchern die notwendigen Ausbildungs- und Ausr\u00fcstungsmanagementf\u00e4higkeiten, um diese Herausforderungen effektiv zu meistern.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Jautajums_Kadi_ir_etiski_apsverumi_nirstot_ekstremala_dziluma\"><\/span>Frage: Welche ethischen \u00dcberlegungen gibt es beim Tauchen in extremen Tiefen?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Verantwortungsvolle Tauchpraktiken m\u00fcssen den Umweltschutz in den Vordergrund stellen und m\u00f6gliche Auswirkungen auf das empfindliche Unterwasser\u00f6kosystem minimieren. Taucher m\u00fcssen die \u00f6rtlichen Vorschriften befolgen, st\u00f6rende Meereslebewesen vermeiden und alle beim Tauchen entstehenden Abf\u00e4lle sorgf\u00e4ltig entsorgen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Celojums_dziluma_kopa_ar_zinasanam\"><\/span>Eine Reise in die Tiefe, gepaart mit Wissen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Die Tiefenbeschr\u00e4nkungen des Ger\u00e4tetauchens stellen das notwendige Gleichgewicht zwischen menschlicher Erkundung und der Erhaltung von Unterwasser\u00f6kosystemen dar. Auch wenn der Reiz tieferer Tauchg\u00e4nge unbestreitbar ist, ist es unerl\u00e4sslich, dass diese Unternehmungen mit Wissen, Erfahrung und tiefem Respekt f\u00fcr die Meeresumwelt angegangen werden. Wenn Taucher die physiologischen und umweltbedingten Einschr\u00e4nkungen verstehen, k\u00f6nnen sie sich auf lohnende und verantwortungsvolle Unterwasserabenteuer einlassen und sicherstellen, dass die Wunder der Tiefe auch kommenden Generationen zug\u00e4nglich bleiben.<\/p>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Patstaviga_nirsanas_prakse_nirstam_dziluma\"><\/span>Unabh\u00e4ngige Tauchpraxis, tief tauchen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Wir bieten Ausbildungen und Praktika f\u00fcr Taucher und zuk\u00fcnftige Taucher an <a href=\"https:\/\/daivings.lv\/padi-divmaster\/\">Tauchlehrer<\/a>\u00a0(<a href=\"https:\/\/daivings.lv\/piedavajam-darba-praksi-daivinga-centra\/\">GO-PRO \u2013 vom Anf\u00e4nger bis zum PADI Divemaster<\/a>). Wir organisieren Tauchausfl\u00fcge,\u00a0<a href=\"https:\/\/daivings.lv\/goto\/https:\/\/www.facebook.com\/daivings\">Folgen Sie uns &gt;&gt;&gt;<\/a>!<\/p>\n<p>Wir bereiten Taucher vor, trainieren und zertifizieren sie, sowohl Tieftaucher als auch <a href=\"https:\/\/daivings.lv\/dry-suit-diver-sertifikats\/\" data-type=\"post\" data-id=\"3633\">Taucher im Trockentauchanzug<\/a>, beide\u00a0<a href=\"https:\/\/daivings.lv\/full-face-mask-diver\/\" data-type=\"post\" data-id=\"4640\">Vollgesichtsmaske Taucher<\/a>\u00a0in Kursen. Wir bieten 30 verschiedene Spezialisierungen in der Ausbildung von Tauchern und der Ausstellung internationaler PADI-Unterwassertauchscheine an.<\/p>\n<p>Wir unterrichten individuelle Tauchausbildungskurse (mit der M\u00f6glichkeit zum Tieftauchen) auf Lettisch, Russisch und Englisch in Riga und Gruppen in ganz Lettland (Voranmeldung erforderlich, Tel.\/<strong>WhatsApp 220-77-202<\/strong>)<\/p>","protected":false},"excerpt":{"rendered":"<p>Tauchen, eine k\u00f6rperlich aktive, adrenalingeladene und aufregende Aktivit\u00e4t, die uns Zugang zu einem au\u00dfergew\u00f6hnlichen Unterwasserreich verschafft, wirft bei Anf\u00e4ngern und Tauchern oft die Frage auf: \u201eWie tief k\u00f6nnen wir gehen?\u201c In diesem Artikel erfahren wir gemeinsam mit dem Tauchclub \u201eDivings\u201c [\u2026]<\/p>","protected":false},"author":1,"featured_media":8533,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zemudens-pasaule"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cik dzi\u013ci varat nirt ar akvalangu? - Daivings.lv<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cik dzi\u013ci varat nirt ar akvalangu? - Daivings.lv\" \/>\n<meta property=\"og:description\" content=\"Nir\u0161ana ar akvalangu, ir fiziski akt\u012bva, adrenal\u012bna pilna un uzmundrino\u0161a darb\u012bba, kas sniedz mums piek\u013cuvi neparastai zem\u016bdens valst\u012bbai, bie\u017ei liek uzdot jaut\u0101jumu ies\u0101c\u0113jiem, nir\u0113jiem- &#8220;Cik dzi\u013ci m\u0113s varam doties dzelm\u0113&#8221;? \u0160aj\u0101 rakst\u0101 m\u0113s noskaidrosim, kop\u0101 ar zem\u016bdens nir\u0161anas kluba &#8220;Daivings&#8221; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Daivings.lv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/daivings\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-04T11:18:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-04T11:36:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"627\" \/>\n\t<meta property=\"og:image:height\" content=\"836\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valters\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@daivings\" \/>\n<meta name=\"twitter:site\" content=\"@daivings\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valters\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/cik-dzili-varat-nirt-ar-akvalangu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/cik-dzili-varat-nirt-ar-akvalangu\\\/\"},\"author\":{\"name\":\"Valters\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/person\\\/2d38bbddcd6444621ca8bcd097565438\"},\"headline\":\"Cik dzi\u013ci varat nirt ar akvalangu?\",\"datePublished\":\"2024-01-04T11:18:38+00:00\",\"dateModified\":\"2024-01-04T11:36:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/cik-dzili-varat-nirt-ar-akvalangu\\\/\"},\"wordCount\":1101,\"publisher\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/cik-dzili-varat-nirt-ar-akvalangu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/daivinga-eksperta-Valtera-Preimana-padoms-4.jpeg?v=1706274991\",\"articleSection\":[\"Zem\u016bdens pasaule\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/cik-dzili-varat-nirt-ar-akvalangu\\\/\",\"url\":\"https:\\\/\\\/daivings.lv\\\/cik-dzili-varat-nirt-ar-akvalangu\\\/\",\"name\":\"Cik dzi\u013ci varat nirt ar akvalangu? - Daivings.lv\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/cik-dzili-varat-nirt-ar-akvalangu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/cik-dzili-varat-nirt-ar-akvalangu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/daivinga-eksperta-Valtera-Preimana-padoms-4.jpeg?v=1706274991\",\"datePublished\":\"2024-01-04T11:18:38+00:00\",\"dateModified\":\"2024-01-04T11:36:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/cik-dzili-varat-nirt-ar-akvalangu\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/daivings.lv\\\/cik-dzili-varat-nirt-ar-akvalangu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/cik-dzili-varat-nirt-ar-akvalangu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/daivinga-eksperta-Valtera-Preimana-padoms-4.jpeg?v=1706274991\",\"contentUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/daivinga-eksperta-Valtera-Preimana-padoms-4.jpeg?v=1706274991\",\"width\":627,\"height\":836,\"caption\":\"Daivinga eksperta Valtera Preima\u0146a padoms (4)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/cik-dzili-varat-nirt-ar-akvalangu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"S\u0101kums\",\"item\":\"https:\\\/\\\/daivings.lv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cik dzi\u013ci varat nirt ar akvalangu?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#website\",\"url\":\"https:\\\/\\\/daivings.lv\\\/\",\"name\":\"Daivings.lv\",\"description\":\"PADI kursi Latvij\u0101, Daivinga klubs pied\u0101v\u0101 nir\u0161anas kursus &amp; PADI Instruktors\",\"publisher\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/daivings.lv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#organization\",\"name\":\"Daivings.lv\",\"url\":\"https:\\\/\\\/daivings.lv\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_recolor.png\",\"contentUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_recolor.png\",\"width\":268,\"height\":70,\"caption\":\"Daivings.lv\"},\"image\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/daivings\\\/\",\"https:\\\/\\\/x.com\\\/daivings\",\"https:\\\/\\\/instagram.com\\\/daivingslv\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/person\\\/2d38bbddcd6444621ca8bcd097565438\",\"name\":\"Valters\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g\",\"caption\":\"Valters\"},\"description\":\"Publik\u0101cijas autors ir aizraut\u012bgs zem\u016bdens nir\u0113js, nir\u0113ju instructors - treneris un profesion\u0101ls fotogr\u0101fs, zem\u016bdens operators. Uzs\u0101cis nir\u0113ja gaitas 2005.gada 20.oktobr\u012b, izejot apm\u0101c\u012bbu Daivinga Instruktoru Profesion\u0101l\u0101 Asoci\u0101cij\u0101, DIPA (Ang. PADI \u2013 Professional Association of Diving Instructors ), tren\u0113jies nir\u0161anas profesion\u0101l\u0101s izaugsmes apm\u0101c\u012bb\u0101 Adrijas un Jonijas j\u016br\u0101s, Zieme\u013cu Atlantijas oke\u0101na sal\u0101s, Sarkan\u0101 j\u016br\u0101, Norv\u0113\u0123u j\u016br\u0101 un Vidusj\u016br\u0101. Piedal\u012bjies zem\u016bdens arheolo\u0123isk\u0101 projekt\u0101 Latvij\u0101. 2006.gada 24.j\u016blij\u0101 izveidojis nir\u0161anas klubu \u201cDaivings.lv\u201d. Paveicis vair\u0101k k\u0101 5000 ienir\u0161anas ar zem\u016bdens elpojamo apar\u0101tu. Piedal\u012bjies daudz\u0101s nir\u0161anas eksped\u012bcij\u0101s, interes\u0113jas par ekolo\u0123iju un to k\u0101 klimata izmai\u0146as ietekm\u0113 zem\u016bdens pasauli.\",\"url\":\"https:\\\/\\\/daivings.lv\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie tief kann man tauchen? - Daivings.lv","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/","og_locale":"de_DE","og_type":"article","og_title":"Cik dzi\u013ci varat nirt ar akvalangu? - Daivings.lv","og_description":"Nir\u0161ana ar akvalangu, ir fiziski akt\u012bva, adrenal\u012bna pilna un uzmundrino\u0161a darb\u012bba, kas sniedz mums piek\u013cuvi neparastai zem\u016bdens valst\u012bbai, bie\u017ei liek uzdot jaut\u0101jumu ies\u0101c\u0113jiem, nir\u0113jiem- &#8220;Cik dzi\u013ci m\u0113s varam doties dzelm\u0113&#8221;? \u0160aj\u0101 rakst\u0101 m\u0113s noskaidrosim, kop\u0101 ar zem\u016bdens nir\u0161anas kluba &#8220;Daivings&#8221; [&hellip;]","og_url":"https:\/\/daivings.lv\/de\/wie-tief-kann-man-tauchen-2\/","og_site_name":"Daivings.lv","article_publisher":"https:\/\/facebook.com\/daivings\/","article_published_time":"2024-01-04T11:18:38+00:00","article_modified_time":"2024-01-04T11:36:37+00:00","og_image":[{"width":627,"height":836,"url":"https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-4.jpeg","type":"image\/jpeg"}],"author":"Valters","twitter_card":"summary_large_image","twitter_creator":"@daivings","twitter_site":"@daivings","twitter_misc":{"Verfasst von":"Valters","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/daivings.lv\/cik-dzili-varat-nirt-ar-akvalangu\/#article","isPartOf":{"@id":"https:\/\/daivings.lv\/cik-dzili-varat-nirt-ar-akvalangu\/"},"author":{"name":"Valters","@id":"https:\/\/daivings.lv\/#\/schema\/person\/2d38bbddcd6444621ca8bcd097565438"},"headline":"Cik dzi\u013ci varat nirt ar akvalangu?","datePublished":"2024-01-04T11:18:38+00:00","dateModified":"2024-01-04T11:36:37+00:00","mainEntityOfPage":{"@id":"https:\/\/daivings.lv\/cik-dzili-varat-nirt-ar-akvalangu\/"},"wordCount":1101,"publisher":{"@id":"https:\/\/daivings.lv\/#organization"},"image":{"@id":"https:\/\/daivings.lv\/cik-dzili-varat-nirt-ar-akvalangu\/#primaryimage"},"thumbnailUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-4.jpeg?v=1706274991","articleSection":["Zem\u016bdens pasaule"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/daivings.lv\/cik-dzili-varat-nirt-ar-akvalangu\/","url":"https:\/\/daivings.lv\/cik-dzili-varat-nirt-ar-akvalangu\/","name":"Wie tief kann man tauchen? - Daivings.lv","isPartOf":{"@id":"https:\/\/daivings.lv\/#website"},"primaryImageOfPage":{"@id":"https:\/\/daivings.lv\/cik-dzili-varat-nirt-ar-akvalangu\/#primaryimage"},"image":{"@id":"https:\/\/daivings.lv\/cik-dzili-varat-nirt-ar-akvalangu\/#primaryimage"},"thumbnailUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-4.jpeg?v=1706274991","datePublished":"2024-01-04T11:18:38+00:00","dateModified":"2024-01-04T11:36:37+00:00","breadcrumb":{"@id":"https:\/\/daivings.lv\/cik-dzili-varat-nirt-ar-akvalangu\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/daivings.lv\/cik-dzili-varat-nirt-ar-akvalangu\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/daivings.lv\/cik-dzili-varat-nirt-ar-akvalangu\/#primaryimage","url":"https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-4.jpeg?v=1706274991","contentUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/daivinga-eksperta-Valtera-Preimana-padoms-4.jpeg?v=1706274991","width":627,"height":836,"caption":"Daivinga eksperta Valtera Preima\u0146a padoms (4)"},{"@type":"BreadcrumbList","@id":"https:\/\/daivings.lv\/cik-dzili-varat-nirt-ar-akvalangu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"S\u0101kums","item":"https:\/\/daivings.lv\/"},{"@type":"ListItem","position":2,"name":"Cik dzi\u013ci varat nirt ar akvalangu?"}]},{"@type":"WebSite","@id":"https:\/\/daivings.lv\/#website","url":"https:\/\/daivings.lv\/","name":"Tauchen.lv","description":"PADI-Kurse in Lettland, Tauchclub bietet Tauchkurse und PADI-Lehrer an","publisher":{"@id":"https:\/\/daivings.lv\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/daivings.lv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/daivings.lv\/#organization","name":"Tauchen.lv","url":"https:\/\/daivings.lv\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/daivings.lv\/#\/schema\/logo\/image\/","url":"https:\/\/daivings.lv\/wp-content\/uploads\/2024\/01\/Logo_recolor.png","contentUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/2024\/01\/Logo_recolor.png","width":268,"height":70,"caption":"Daivings.lv"},"image":{"@id":"https:\/\/daivings.lv\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/daivings\/","https:\/\/x.com\/daivings","https:\/\/instagram.com\/daivingslv\/"]},{"@type":"Person","@id":"https:\/\/daivings.lv\/#\/schema\/person\/2d38bbddcd6444621ca8bcd097565438","name":"Walter","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g","caption":"Valters"},"description":"Der Autor der Publikation ist ein leidenschaftlicher Unterwassertaucher, Tauchlehrer \u2013 Trainer und professioneller Fotograf, Unterwasseroperator. Begann am 20. Oktober 2005 mit dem Tauchen und absolvierte eine Ausbildung beim Berufsverband der Tauchlehrer DIPA (dt. PADI \u2013 Berufsverband der Tauchlehrer). Er absolvierte eine Berufsausbildung f\u00fcr das Tauchen in der Adria und im Ionischen Meer sowie auf den Inseln des Nordens Atlantischer Ozean, Rotes Meer, Norwegisches Meer und im Mittelmeer. Teilnahme an einem Unterwasserarch\u00e4ologieprojekt in Lettland. Am 24. Juli 2006 gr\u00fcndete er den Tauchclub \u201eDaivings.lv\u201c. Mehr als 5000 Tauchg\u00e4nge gemacht. Hat an vielen Tauchexpeditionen teilgenommen, interessiert sich f\u00fcr \u00d6kologie und wie sich der Klimawandel auf die Unterwasserwelt auswirkt.","url":"https:\/\/daivings.lv\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/posts\/8930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/comments?post=8930"}],"version-history":[{"count":0,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/posts\/8930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/media\/8533"}],"wp:attachment":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/media?parent=8930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/categories?post=8930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/tags?post=8930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}