{"id":8239,"date":"2023-05-05T05:43:36","date_gmt":"2023-05-05T05:43:36","guid":{"rendered":"https:\/\/daivings.lv\/?p=8239"},"modified":"2024-02-22T10:07:12","modified_gmt":"2024-02-22T10:07:12","slug":"nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss","status":"publish","type":"post","link":"https:\/\/daivings.lv\/de\/tauchausrustungstechniker-spezialist-tauchaufsichtsdienst\/","title":{"rendered":"Techniker f\u00fcr Tauchausr\u00fcstung \u2013 Spezialist, Service f\u00fcr Tauchregler"},"content":{"rendered":"<p>Unterwassertauchen ist ein herausfordernder, interessanter und lohnender Beruf, der ein hohes Ma\u00df an K\u00f6nnen und Wissen erfordert. Eine der wichtigsten Rollen beim Freizeit- und Berufstauchen ist die eines Tauchausr\u00fcstungsspezialisten. Diese Tauchausr\u00fcstungstechniker \u2013 Fachkr\u00e4fte sind f\u00fcr die Wartung und Instandhaltung der Tauchausr\u00fcstung, einschlie\u00dflich Atemregler und Schwimmwesten, verantwortlich. In diesem Artikel werfen wir einen genaueren Blick auf die Verantwortlichkeiten eines Tauchausr\u00fcstungsspezialisten und untersuchen die Standard- und Wartungsverfahren bei der Wartung eines Tauchreglers.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Inhaltsverzeichnis ein-\/ausblenden\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Umschalten<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/daivings.lv\/de\/tauchausrustungstechniker-spezialist-tauchaufsichtsdienst\/#Ka_pieteikt_nirsanas_regulatoru_tehniskajai_apkopei_nirsanas_regulatora_serviss\" >Wie beantrage ich die Wartung des Tauchreglers oder den Service f\u00fcr den Tauchregler?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/daivings.lv\/de\/tauchausrustungstechniker-spezialist-tauchaufsichtsdienst\/#Nirsanas_aprikojuma_specialista_pienakumi\" >Aufgaben eines Tauchausr\u00fcstungsspezialisten<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/daivings.lv\/de\/tauchausrustungstechniker-spezialist-tauchaufsichtsdienst\/#Nirsanas_regulatora_ikgadeja_apkalposanas_kartiba\" >J\u00e4hrlicher Servicevorgang des Tauchreglers<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/daivings.lv\/de\/tauchausrustungstechniker-spezialist-tauchaufsichtsdienst\/#Nirsanas_aprikojuma_standarta_proceduras\" >Standardverfahren f\u00fcr Tauchausr\u00fcstung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/daivings.lv\/de\/tauchausrustungstechniker-spezialist-tauchaufsichtsdienst\/#Nirsanas_apkopes_proceduras\" >Wartungsverfahren f\u00fcr das Tauchen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/daivings.lv\/de\/tauchausrustungstechniker-spezialist-tauchaufsichtsdienst\/#Apgusti_%E2%80%9CPADI_Equipment_Specialist%E2%80%9D_iemanas_specialitate\" >Erlernen Sie die Fertigkeiten \u201ePADI Equipment Specialist\u201c in der Spezialit\u00e4t<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/daivings.lv\/de\/tauchausrustungstechniker-spezialist-tauchaufsichtsdienst\/#Atsauces\" >Verweise<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Ka_pieteikt_nirsanas_regulatoru_tehniskajai_apkopei_nirsanas_regulatora_serviss\"><\/span>Wie beantrage ich die Wartung des Tauchreglers oder den Service f\u00fcr den Tauchregler?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Informieren Sie sich \u00fcber den Namen und das Modell des Herstellers Ihres Atemreglers oder Ihrer Tarierweste<\/li>\n<li>Wir akzeptieren zur Wartung <strong>Cressi<\/strong>, <strong>Apeks<\/strong> Und <strong>Aqualung<\/strong> Aufsichtsbeh\u00f6rden<\/li>\n<li>Erfahren Sie, wie schnell Original-Service-Reparaturteile verf\u00fcgbar sind<\/li>\n<li>Rufen Sie einen Spezialisten unter der unten angegebenen Telefonnummer an<\/li>\n<\/ul>\n<p><b>Wartung des Atemreglers - \u201eDronelab\u201c SIA, Telefon Tel. 220-77-202, E-Mail: mail@dronelab.lv<\/b><\/p>\n<figure id=\"attachment_8241\" aria-describedby=\"caption-attachment-8241\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnika-specialista-pienakumi-nirsanas-regulatora-serviss\/cressi-technical-seminar-2-days\/\" rel=\"attachment wp-att-8241\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8241 size-medium\" src=\"https:\/\/daivings.lv\/wp-content\/uploads\/Cressi-Technical-Seminar-2-days-300x217.jpg\" alt=\"Zertifikat als Wartungstechniker f\u00fcr Tauchregler\" width=\"300\" height=\"217\" srcset=\"https:\/\/daivings.lv\/wp-content\/uploads\/Cressi-Technical-Seminar-2-days-300x217.jpg?v=1706275059 300w, https:\/\/daivings.lv\/wp-content\/uploads\/Cressi-Technical-Seminar-2-days-1024x740.jpg?v=1706275059 1024w, https:\/\/daivings.lv\/wp-content\/uploads\/Cressi-Technical-Seminar-2-days-768x555.jpg?v=1706275059 768w, https:\/\/daivings.lv\/wp-content\/uploads\/Cressi-Technical-Seminar-2-days-18x12.jpg?v=1706275059 18w, https:\/\/daivings.lv\/wp-content\/uploads\/Cressi-Technical-Seminar-2-days-1000x722.jpg?v=1706275059 1000w, https:\/\/daivings.lv\/wp-content\/uploads\/Cressi-Technical-Seminar-2-days-550x400.jpg?v=1706275059 550w, https:\/\/daivings.lv\/wp-content\/uploads\/Cressi-Technical-Seminar-2-days-230x166.jpg?v=1706275059 230w, https:\/\/daivings.lv\/wp-content\/uploads\/Cressi-Technical-Seminar-2-days-350x253.jpg?v=1706275059 350w, https:\/\/daivings.lv\/wp-content\/uploads\/Cressi-Technical-Seminar-2-days-480x347.jpg?v=1706275059 480w, https:\/\/daivings.lv\/wp-content\/uploads\/Cressi-Technical-Seminar-2-days.jpg?v=1706275059 1469w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-8241\" class=\"wp-caption-text\">Zertifikat als Wartungstechniker f\u00fcr Tauchregler<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Nirsanas_aprikojuma_specialista_pienakumi\"><\/span>Aufgaben eines Tauchausr\u00fcstungsspezialisten<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Die Hauptverantwortung eines Tauchausr\u00fcstungsspezialisten besteht darin, sicherzustellen, dass die gesamte Tauchausr\u00fcstung auf dem h\u00f6chstm\u00f6glichen Niveau gewartet und gewartet wird. Dazu geh\u00f6rt alles von Neoprenanz\u00fcgen und Masken bis hin zu Atemreglern und Flaschen. Zu den spezifischen Aufgaben eines Tauchausr\u00fcstungsspezialisten k\u00f6nnen geh\u00f6ren:<\/p>\n<ul>\n<li>Regelm\u00e4\u00dfige Inspektionen der Tauchausr\u00fcstung, um sicherzustellen, dass sie in gutem Zustand ist.<\/li>\n<li>Identifizieren und Beheben von Fehlfunktionen oder Problemen mit Tauchausr\u00fcstung, einschlie\u00dflich Tauchreglern.<\/li>\n<li>Service und Wartung von Tauchausr\u00fcstung, einschlie\u00dflich Atemreglern, um sicherzustellen, dass diese f\u00fcr den Einsatz im kommerziellen Tauchbetrieb sicher und effektiv ist.<\/li>\n<li>Genaue Aufzeichnungen aller Inspektionen, Wartungs- und Serviceaktivit\u00e4ten der Tauchausr\u00fcstung.<\/li>\n<\/ul>\n<figure id=\"attachment_6943\" aria-describedby=\"caption-attachment-6943\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/daivings.lv\/drosiba-zem-udens-un-regularas-ekipejuma-apkopes\/regulatora_apkopes_tehnika_sertifikats\/\" rel=\"attachment wp-att-6943\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6943\" src=\"https:\/\/daivings.lv\/wp-content\/uploads\/Regulatora_apkopes_tehnika_sertifikats-300x178.png\" alt=\"Zertifikat als Wartungstechniker f\u00fcr Tauchregler\" width=\"300\" height=\"178\" srcset=\"https:\/\/daivings.lv\/wp-content\/uploads\/Regulatora_apkopes_tehnika_sertifikats-300x178.png?v=1706275357 300w, https:\/\/daivings.lv\/wp-content\/uploads\/Regulatora_apkopes_tehnika_sertifikats-1024x606.png?v=1706275357 1024w, https:\/\/daivings.lv\/wp-content\/uploads\/Regulatora_apkopes_tehnika_sertifikats-768x454.png?v=1706275357 768w, https:\/\/daivings.lv\/wp-content\/uploads\/Regulatora_apkopes_tehnika_sertifikats-18x12.png?v=1706275357 18w, https:\/\/daivings.lv\/wp-content\/uploads\/Regulatora_apkopes_tehnika_sertifikats-1000x592.png?v=1706275357 1000w, https:\/\/daivings.lv\/wp-content\/uploads\/Regulatora_apkopes_tehnika_sertifikats-230x136.png?v=1706275357 230w, https:\/\/daivings.lv\/wp-content\/uploads\/Regulatora_apkopes_tehnika_sertifikats-350x207.png?v=1706275357 350w, https:\/\/daivings.lv\/wp-content\/uploads\/Regulatora_apkopes_tehnika_sertifikats-480x284.png?v=1706275357 480w, https:\/\/daivings.lv\/wp-content\/uploads\/Regulatora_apkopes_tehnika_sertifikats.png?v=1706275357 1433w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-6943\" class=\"wp-caption-text\">Zertifikat als Wartungstechniker f\u00fcr Tauchregler<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Nirsanas_regulatora_ikgadeja_apkalposanas_kartiba\"><\/span>J\u00e4hrlicher Servicevorgang des Tauchreglers<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Einer der wichtigsten Aspekte der Wartung von Tauchausr\u00fcstung ist die Wartung des Atemreglers. Ein Atemregler ist ein Ger\u00e4t, das es Tauchern erm\u00f6glicht, unter Wasser Luft aus einer Tauchflasche zu atmen. Daher ist es wichtig, dass Atemregler ordnungsgem\u00e4\u00df gewartet und gewartet werden, um die Sicherheit der Taucher zu gew\u00e4hrleisten. Ein Tauchregler sollte einmal im Jahr oder h\u00e4ufiger gewartet werden, wenn es sich um ein Tauchcenter handelt.<\/p>\n<figure id=\"attachment_8240\" aria-describedby=\"caption-attachment-8240\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnika-specialista-pienakumi-nirsanas-regulatora-serviss\/commercial-diving-is-a-challenging-and-rewarding-profession-that-requires-a-high-level-of-skill-and-expertise\/\" rel=\"attachment wp-att-8240\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8240\" src=\"https:\/\/daivings.lv\/wp-content\/uploads\/Commercial-diving-is-a-challenging-and-rewarding-profession-that-requires-a-high-level-of-skill-and-expertise-300x169.png\" alt=\"Servicetechniker f\u00fcr Tauchausr\u00fcstung\" width=\"300\" height=\"169\" srcset=\"https:\/\/daivings.lv\/wp-content\/uploads\/Commercial-diving-is-a-challenging-and-rewarding-profession-that-requires-a-high-level-of-skill-and-expertise-300x169.png?v=1706275062 300w, https:\/\/daivings.lv\/wp-content\/uploads\/Commercial-diving-is-a-challenging-and-rewarding-profession-that-requires-a-high-level-of-skill-and-expertise-1024x576.png?v=1706275062 1024w, https:\/\/daivings.lv\/wp-content\/uploads\/Commercial-diving-is-a-challenging-and-rewarding-profession-that-requires-a-high-level-of-skill-and-expertise-768x432.png?v=1706275062 768w, https:\/\/daivings.lv\/wp-content\/uploads\/Commercial-diving-is-a-challenging-and-rewarding-profession-that-requires-a-high-level-of-skill-and-expertise-1536x864.png?v=1706275062 1536w, https:\/\/daivings.lv\/wp-content\/uploads\/Commercial-diving-is-a-challenging-and-rewarding-profession-that-requires-a-high-level-of-skill-and-expertise-18x10.png?v=1706275062 18w, https:\/\/daivings.lv\/wp-content\/uploads\/Commercial-diving-is-a-challenging-and-rewarding-profession-that-requires-a-high-level-of-skill-and-expertise-1000x563.png?v=1706275062 1000w, https:\/\/daivings.lv\/wp-content\/uploads\/Commercial-diving-is-a-challenging-and-rewarding-profession-that-requires-a-high-level-of-skill-and-expertise-230x129.png?v=1706275062 230w, https:\/\/daivings.lv\/wp-content\/uploads\/Commercial-diving-is-a-challenging-and-rewarding-profession-that-requires-a-high-level-of-skill-and-expertise-350x197.png?v=1706275062 350w, https:\/\/daivings.lv\/wp-content\/uploads\/Commercial-diving-is-a-challenging-and-rewarding-profession-that-requires-a-high-level-of-skill-and-expertise-480x270.png?v=1706275062 480w, https:\/\/daivings.lv\/wp-content\/uploads\/Commercial-diving-is-a-challenging-and-rewarding-profession-that-requires-a-high-level-of-skill-and-expertise.png?v=1706275062 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-8240\" class=\"wp-caption-text\">Servicetechniker f\u00fcr Tauchausr\u00fcstung im Wasser<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Nirsanas_aprikojuma_standarta_proceduras\"><\/span>Standardverfahren f\u00fcr Tauchausr\u00fcstung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>Standardverfahren f\u00fcr die Wartung von Atemreglern umfassen im Allgemeinen mehrere wichtige Schritte. Dazu k\u00f6nnen geh\u00f6ren:<\/strong><\/p>\n<ul>\n<li>Zerlegen Sie den Regler und reinigen Sie alle Teile, um eventuelle R\u00fcckst\u00e4nde und Verunreinigungen zu entfernen.<\/li>\n<li>\u00dcberpr\u00fcfen Sie alle Reglerkomponenten auf Sch\u00e4den oder Anzeichen von Verschlei\u00df, einschlie\u00dflich Membranen, Ventilsitzen und Dichtungen.<\/li>\n<li>Austausch aller verschlissenen oder besch\u00e4digten Teile, einschlie\u00dflich verschlissener oder besch\u00e4digter Membranen, Ventilsitze oder Dichtungen.<\/li>\n<li>Zusammenbau und Test des Reglers, um sicherzustellen, dass er ordnungsgem\u00e4\u00df funktioniert.<\/li>\n<li>Ein Tauchregler sollte einmal im Jahr oder h\u00e4ufiger gewartet werden, wenn es sich um ein Tauchcenter handelt.<\/li>\n<li>Es ist wichtig, den Tauchregler nach jedem Tauchgang zu pflegen, die Staubkappe t\u00e4glich aufzuschrauben und zu verwenden und den Atemregler sowohl in der ersten als auch in der zweiten Stufe mit S\u00fc\u00dfwasser zu sp\u00fclen.<\/li>\n<\/ul>\n<figure id=\"attachment_5614\" aria-describedby=\"caption-attachment-5614\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/daivings.lv\/nirsanas-ekipejuma-apkope\/nirsanas-regulatora-apkope\/\" rel=\"attachment wp-att-5614\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5614\" src=\"https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-regulatora-apkope-300x225.jpg\" alt=\"Wartung des Tauchreglers\" width=\"300\" height=\"225\" srcset=\"https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-regulatora-apkope-300x225.jpg?v=1706275487 300w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-regulatora-apkope-768x576.jpg?v=1706275487 768w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-regulatora-apkope-16x12.jpg?v=1706275487 16w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-regulatora-apkope-230x173.jpg?v=1706275487 230w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-regulatora-apkope-350x263.jpg?v=1706275487 350w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-regulatora-apkope-480x360.jpg?v=1706275487 480w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-regulatora-apkope.jpg?v=1706275487 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-5614\" class=\"wp-caption-text\">Es ist wichtig, nach jedem Tauchgang auf den Atemregler zu achten.<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Nirsanas_apkopes_proceduras\"><\/span>Wartungsverfahren f\u00fcr das Tauchen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>Zus\u00e4tzlich zu den Standardwartungsverfahren f\u00fcr Tauchregler gibt es mehrere Wartungsverfahren, die dazu beitragen k\u00f6nnen, die Lebensdauer von Tauchreglern zu verl\u00e4ngern und ihre sichere und effiziente Verwendung zu gew\u00e4hrleisten. Dazu k\u00f6nnen geh\u00f6ren:<\/strong><\/p>\n<ul>\n<li>Tauschen Sie alle beweglichen Teile des Reglers regelm\u00e4\u00dfig aus, um Korrosion und Verschlei\u00df vorzubeugen.<\/li>\n<li>Bewahren Sie Atemregler an einem trockenen, k\u00fchlen Ort auf, um Feuchtigkeitsansammlungen zu vermeiden.<\/li>\n<li>Vermeiden Sie den Kontakt mit \u00e4tzenden Chemikalien oder L\u00f6sungsmitteln, die den Regler besch\u00e4digen k\u00f6nnten.<\/li>\n<\/ul>\n<figure id=\"attachment_8249\" aria-describedby=\"caption-attachment-8249\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnika-specialista-pienakumi-nirsanas-regulatora-serviss\/nirsanas-ekipejuma-regulatora-tehnikis\/\" rel=\"attachment wp-att-8249\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8249 size-medium\" src=\"https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated-300x225.jpg\" alt=\"Atemreglertechniker f\u00fcr Tauchausr\u00fcstung\" width=\"300\" height=\"225\" srcset=\"https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated-300x225.jpg?v=1706275058 300w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated-1024x768.jpg?v=1706275058 1024w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated-768x576.jpg?v=1706275058 768w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated-1536x1152.jpg?v=1706275058 1536w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated-16x12.jpg?v=1706275058 16w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated-1000x750.jpg?v=1706275058 1000w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated-230x173.jpg?v=1706275058 230w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated-350x263.jpg?v=1706275058 350w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated-480x360.jpg?v=1706275058 480w, https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated.jpg?v=1706275058 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-8249\" class=\"wp-caption-text\">Atemreglertechniker f\u00fcr Tauchausr\u00fcstung<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Apgusti_%E2%80%9CPADI_Equipment_Specialist%E2%80%9D_iemanas_specialitate\"><\/span>Erlernen Sie die Fertigkeiten \u201ePADI Equipment Specialist\u201c in der Spezialit\u00e4t<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Verpassen Sie keinen Tauchgang wegen eines geringf\u00fcgigen Problems mit Ihrer Tauchausr\u00fcstung. Egal, ob es sich um einen fehlenden O-Ring, eine gerissene Naht eines Neoprenanzugs oder einen gerissenen Flossenriemen handelt, im PADI Equipment Specialist-Kurs lernen Sie grundlegende Reparaturen und Wartung. Au\u00dferdem erfahren Sie mehr \u00fcber die Funktionsweise Ihrer Ausr\u00fcstung, sodass Sie sich wohler f\u00fchlen und besser f\u00fcr die Verwaltung Ihrer Investition ger\u00fcstet sind.<\/p>\n<p>Wenn Sie mindestens 10 Jahre alt und als PADI (Junior) Taucher oder h\u00f6her zertifiziert sind, k\u00f6nnen Sie sich f\u00fcr den Ausr\u00fcstungsspezialistenkurs anmelden \u2013 \u201e<a href=\"https:\/\/daivings.lv\/padi-equipment-specialist-kursi-un-sertifikats\/\"><strong>PADI-Ausr\u00fcstungsspezialist<\/strong><\/a>&#8220;.<\/p>\n<p>Kontaktieren Sie uns bez\u00fcglich der Kurse, indem Sie eine Nachricht schreiben oder \u00fcber schreiben <strong><a href=\"https:\/\/daivings.lv\/kontakti\/\">Kontakt Formular<\/a><\/strong><\/p>\n<p>Die Aufgaben eines Tauchausr\u00fcstungsspezialisten sind f\u00fcr den sicheren und effizienten Einsatz von Tauchausr\u00fcstung bei kommerziellen Taucheins\u00e4tzen von entscheidender Bedeutung. Durch die Befolgung der standardm\u00e4\u00dfigen Service- und Wartungsverfahren f\u00fcr Atemregler k\u00f6nnen Tauchausr\u00fcstungsspezialisten dazu beitragen, die Sicherheit von Tauchern und den Erfolg kommerzieller Taucheins\u00e4tze zu gew\u00e4hrleisten. Und vergessen wir nicht: Sie k\u00f6nnen auch diese coolen Neoprenanz\u00fcge tragen und so tun, als w\u00e4ren sie Superhelden im Wasser.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Atsauces\"><\/span>Verweise<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ol>\n<li><a href=\"https:\/\/daivings.lv\/nirsanas-ekipejuma-apkope\/\">Wartung von Tauchausr\u00fcstung (DIVING)<\/a><\/li>\n<li><a href=\"https:\/\/daivings.lv\/padi-equipment-specialist-kursi-un-sertifikats\/\">PADI-Ausr\u00fcstungsspezialist (TAUCHEN)<\/a><\/li>\n<li><a href=\"https:\/\/daivings.lv\/ka-rupeties-par-nirsanas-un-daivinga-masku-pieci-noderigi-padomi\/\">Wie pflegt man einen Taucher und eine Tauchermaske (TAUCHEN)<\/a><\/li>\n<li><a href=\"https:\/\/daivings.lv\/drosiba-zem-udens-un-regularas-ekipejuma-apkopes\/\">Unterwassersicherheit und regelm\u00e4\u00dfige Wartung der Ausr\u00fcstung\u00a0<\/a><\/li>\n<li>\u201eTauchausr\u00fcstungsspezialist\u201c \u2013 Berufsverband der Tauchlehrer (PADI)<\/li>\n<li>\u201eWartung und Wartung von Tauchausr\u00fcstung\u201c \u2013 Health and Safety Executive (HSE)<\/li>\n<li>\u201eTauchreglerwartung\u201c \u2013 Zeitschrift \u201eScuba Diving\u201c.<\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>Unterwassertauchen ist ein herausfordernder, interessanter und lohnender Beruf, der ein hohes Ma\u00df an K\u00f6nnen und Wissen erfordert. Eine der wichtigsten Rollen beim Freizeit- und Berufstauchen ist die eines Tauchausr\u00fcstungsspezialisten. Diese Tauchausr\u00fcstungstechniker - Fachkr\u00e4fte sind f\u00fcr die Wartung der Tauchausr\u00fcstung verantwortlich, einschlie\u00dflich der Tauchausr\u00fcstung [...]<\/p>","protected":false},"author":1,"featured_media":8249,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-8239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-daivinga-ekipejums"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nir\u0161anas apr\u012bkojuma tehni\u0137is- speci\u0101lists, nir\u0161anas regulatora serviss - Daivings.lv<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/daivings.lv\/de\/tauchausrustungstechniker-spezialist-tauchaufsichtsdienst\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nir\u0161anas apr\u012bkojuma tehni\u0137is- speci\u0101lists, nir\u0161anas regulatora serviss - Daivings.lv\" \/>\n<meta property=\"og:description\" content=\"Zem\u016bdens nir\u0161ana ir izaicino\u0161a, interesanta un atalgojo\u0161a profesija, kas prasa augsta l\u012bme\u0146a prasmes un zin\u0101\u0161anas. Viena no svar\u012bg\u0101kaj\u0101m lom\u0101m atp\u016btas un komerci\u0101laj\u0101 nir\u0161an\u0101 ir nir\u0161anas apr\u012bkojuma speci\u0101lista loma. \u0160ie nir\u0161anas apr\u012bkojuma tehni\u0137i -profesion\u0101\u013ci ir atbild\u012bgi par nir\u0161anas apr\u012bkojuma, tostarp nir\u0161anas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/daivings.lv\/de\/tauchausrustungstechniker-spezialist-tauchaufsichtsdienst\/\" \/>\n<meta property=\"og:site_name\" content=\"Daivings.lv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/daivings\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-05T05:43:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-22T10:07:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated.jpg?v=1706275058\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valters\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@daivings\" \/>\n<meta name=\"twitter:site\" content=\"@daivings\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valters\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\\\/\"},\"author\":{\"name\":\"Valters\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/person\\\/2d38bbddcd6444621ca8bcd097565438\"},\"headline\":\"Nir\u0161anas apr\u012bkojuma tehni\u0137is- speci\u0101lists, nir\u0161anas regulatora serviss\",\"datePublished\":\"2023-05-05T05:43:36+00:00\",\"dateModified\":\"2024-02-22T10:07:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\\\/\"},\"wordCount\":1090,\"publisher\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated.jpg?v=1706275058\",\"articleSection\":[\"Daivinga ekip\u0113jums\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\\\/\",\"url\":\"https:\\\/\\\/daivings.lv\\\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\\\/\",\"name\":\"Nir\u0161anas apr\u012bkojuma tehni\u0137is- speci\u0101lists, nir\u0161anas regulatora serviss - Daivings.lv\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated.jpg?v=1706275058\",\"datePublished\":\"2023-05-05T05:43:36+00:00\",\"dateModified\":\"2024-02-22T10:07:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/daivings.lv\\\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\\\/#primaryimage\",\"url\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated.jpg?v=1706275058\",\"contentUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated.jpg?v=1706275058\",\"width\":2048,\"height\":1536,\"caption\":\"Nir\u0161anas ekip\u0113juma regul\u0101tora tehni\u0137is\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"S\u0101kums\",\"item\":\"https:\\\/\\\/daivings.lv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nir\u0161anas apr\u012bkojuma tehni\u0137is- speci\u0101lists, nir\u0161anas regulatora serviss\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#website\",\"url\":\"https:\\\/\\\/daivings.lv\\\/\",\"name\":\"Daivings.lv\",\"description\":\"PADI kursi Latvij\u0101, Daivinga klubs pied\u0101v\u0101 nir\u0161anas kursus &amp; PADI Instruktors\",\"publisher\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/daivings.lv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#organization\",\"name\":\"Daivings.lv\",\"url\":\"https:\\\/\\\/daivings.lv\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_recolor.png\",\"contentUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_recolor.png\",\"width\":268,\"height\":70,\"caption\":\"Daivings.lv\"},\"image\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/daivings\\\/\",\"https:\\\/\\\/x.com\\\/daivings\",\"https:\\\/\\\/instagram.com\\\/daivingslv\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/person\\\/2d38bbddcd6444621ca8bcd097565438\",\"name\":\"Valters\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g\",\"caption\":\"Valters\"},\"description\":\"Publik\u0101cijas autors ir aizraut\u012bgs zem\u016bdens nir\u0113js, nir\u0113ju instructors - treneris un profesion\u0101ls fotogr\u0101fs, zem\u016bdens operators. Uzs\u0101cis nir\u0113ja gaitas 2005.gada 20.oktobr\u012b, izejot apm\u0101c\u012bbu Daivinga Instruktoru Profesion\u0101l\u0101 Asoci\u0101cij\u0101, DIPA (Ang. PADI \u2013 Professional Association of Diving Instructors ), tren\u0113jies nir\u0161anas profesion\u0101l\u0101s izaugsmes apm\u0101c\u012bb\u0101 Adrijas un Jonijas j\u016br\u0101s, Zieme\u013cu Atlantijas oke\u0101na sal\u0101s, Sarkan\u0101 j\u016br\u0101, Norv\u0113\u0123u j\u016br\u0101 un Vidusj\u016br\u0101. Piedal\u012bjies zem\u016bdens arheolo\u0123isk\u0101 projekt\u0101 Latvij\u0101. 2006.gada 24.j\u016blij\u0101 izveidojis nir\u0161anas klubu \u201cDaivings.lv\u201d. Paveicis vair\u0101k k\u0101 5000 ienir\u0161anas ar zem\u016bdens elpojamo apar\u0101tu. Piedal\u012bjies daudz\u0101s nir\u0161anas eksped\u012bcij\u0101s, interes\u0113jas par ekolo\u0123iju un to k\u0101 klimata izmai\u0146as ietekm\u0113 zem\u016bdens pasauli.\",\"url\":\"https:\\\/\\\/daivings.lv\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Techniker f\u00fcr Tauchausr\u00fcstung \u2013 Spezialist, Service f\u00fcr Tauchregler \u2013 Daivings.lv","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/daivings.lv\/de\/tauchausrustungstechniker-spezialist-tauchaufsichtsdienst\/","og_locale":"de_DE","og_type":"article","og_title":"Nir\u0161anas apr\u012bkojuma tehni\u0137is- speci\u0101lists, nir\u0161anas regulatora serviss - Daivings.lv","og_description":"Zem\u016bdens nir\u0161ana ir izaicino\u0161a, interesanta un atalgojo\u0161a profesija, kas prasa augsta l\u012bme\u0146a prasmes un zin\u0101\u0161anas. Viena no svar\u012bg\u0101kaj\u0101m lom\u0101m atp\u016btas un komerci\u0101laj\u0101 nir\u0161an\u0101 ir nir\u0161anas apr\u012bkojuma speci\u0101lista loma. \u0160ie nir\u0161anas apr\u012bkojuma tehni\u0137i -profesion\u0101\u013ci ir atbild\u012bgi par nir\u0161anas apr\u012bkojuma, tostarp nir\u0161anas [&hellip;]","og_url":"https:\/\/daivings.lv\/de\/tauchausrustungstechniker-spezialist-tauchaufsichtsdienst\/","og_site_name":"Daivings.lv","article_publisher":"https:\/\/facebook.com\/daivings\/","article_published_time":"2023-05-05T05:43:36+00:00","article_modified_time":"2024-02-22T10:07:12+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated.jpg?v=1706275058","type":"image\/jpeg"}],"author":"Valters","twitter_card":"summary_large_image","twitter_creator":"@daivings","twitter_site":"@daivings","twitter_misc":{"Verfasst von":"Valters","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\/#article","isPartOf":{"@id":"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\/"},"author":{"name":"Valters","@id":"https:\/\/daivings.lv\/#\/schema\/person\/2d38bbddcd6444621ca8bcd097565438"},"headline":"Nir\u0161anas apr\u012bkojuma tehni\u0137is- speci\u0101lists, nir\u0161anas regulatora serviss","datePublished":"2023-05-05T05:43:36+00:00","dateModified":"2024-02-22T10:07:12+00:00","mainEntityOfPage":{"@id":"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\/"},"wordCount":1090,"publisher":{"@id":"https:\/\/daivings.lv\/#organization"},"image":{"@id":"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\/#primaryimage"},"thumbnailUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated.jpg?v=1706275058","articleSection":["Daivinga ekip\u0113jums"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\/","url":"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\/","name":"Techniker f\u00fcr Tauchausr\u00fcstung \u2013 Spezialist, Service f\u00fcr Tauchregler \u2013 Daivings.lv","isPartOf":{"@id":"https:\/\/daivings.lv\/#website"},"primaryImageOfPage":{"@id":"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\/#primaryimage"},"image":{"@id":"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\/#primaryimage"},"thumbnailUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated.jpg?v=1706275058","datePublished":"2023-05-05T05:43:36+00:00","dateModified":"2024-02-22T10:07:12+00:00","breadcrumb":{"@id":"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\/#primaryimage","url":"https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated.jpg?v=1706275058","contentUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/Nirsanas-ekipejuma-regulatora-tehnikis-rotated.jpg?v=1706275058","width":2048,"height":1536,"caption":"Nir\u0161anas ekip\u0113juma regul\u0101tora tehni\u0137is"},{"@type":"BreadcrumbList","@id":"https:\/\/daivings.lv\/nirsanas-aprikojuma-tehnikis-specialists-nirsanas-regulatora-serviss\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"S\u0101kums","item":"https:\/\/daivings.lv\/"},{"@type":"ListItem","position":2,"name":"Nir\u0161anas apr\u012bkojuma tehni\u0137is- speci\u0101lists, nir\u0161anas regulatora serviss"}]},{"@type":"WebSite","@id":"https:\/\/daivings.lv\/#website","url":"https:\/\/daivings.lv\/","name":"Tauchen.lv","description":"PADI-Kurse in Lettland, Tauchclub bietet Tauchkurse und PADI-Lehrer an","publisher":{"@id":"https:\/\/daivings.lv\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/daivings.lv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/daivings.lv\/#organization","name":"Tauchen.lv","url":"https:\/\/daivings.lv\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/daivings.lv\/#\/schema\/logo\/image\/","url":"https:\/\/daivings.lv\/wp-content\/uploads\/2024\/01\/Logo_recolor.png","contentUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/2024\/01\/Logo_recolor.png","width":268,"height":70,"caption":"Daivings.lv"},"image":{"@id":"https:\/\/daivings.lv\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/daivings\/","https:\/\/x.com\/daivings","https:\/\/instagram.com\/daivingslv\/"]},{"@type":"Person","@id":"https:\/\/daivings.lv\/#\/schema\/person\/2d38bbddcd6444621ca8bcd097565438","name":"Walter","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g","caption":"Valters"},"description":"Der Autor der Publikation ist ein leidenschaftlicher Unterwassertaucher, Tauchlehrer \u2013 Trainer und professioneller Fotograf, Unterwasseroperator. Begann am 20. Oktober 2005 mit dem Tauchen und absolvierte eine Ausbildung beim Berufsverband der Tauchlehrer DIPA (dt. PADI \u2013 Berufsverband der Tauchlehrer). Er absolvierte eine Berufsausbildung f\u00fcr das Tauchen in der Adria und im Ionischen Meer sowie auf den Inseln des Nordens Atlantischer Ozean, Rotes Meer, Norwegisches Meer und im Mittelmeer. Teilnahme an einem Unterwasserarch\u00e4ologieprojekt in Lettland. Am 24. Juli 2006 gr\u00fcndete er den Tauchclub \u201eDaivings.lv\u201c. Mehr als 5000 Tauchg\u00e4nge gemacht. Hat an vielen Tauchexpeditionen teilgenommen, interessiert sich f\u00fcr \u00d6kologie und wie sich der Klimawandel auf die Unterwasserwelt auswirkt.","url":"https:\/\/daivings.lv\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/posts\/8239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/comments?post=8239"}],"version-history":[{"count":0,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/posts\/8239\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/media\/8249"}],"wp:attachment":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/media?parent=8239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/categories?post=8239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/tags?post=8239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}