{"id":106,"date":"2007-04-08T07:26:51","date_gmt":"2007-04-08T07:26:51","guid":{"rendered":"https:\/\/daivings.lv\/?p=106"},"modified":"2011-02-27T07:35:07","modified_gmt":"2011-02-27T07:35:07","slug":"kas-ir-dir-doing-it-right-sistema","status":"publish","type":"post","link":"https:\/\/daivings.lv\/de\/das-ist-das-verzeichnis-das-es-richtig-macht\/","title":{"rendered":"Was ist das DIR (Doing It Right)-System?"},"content":{"rendered":"<p><strong>DIR-Systeme<\/strong> Es basiert auf Einstellungen und Werten gegen\u00fcber dem Tauchen und ist nicht nur ein System von Tauchausr\u00fcstung, wie viele Taucher denken. Daivings ist ein tolles Hobby und sollte auf sichere Weise durchgef\u00fchrt werden. Mit \u201eSicherheit\u201c meinen wir, dass der Taucher keine unn\u00f6tigen Risiken eingeht, was die erste Regel des DIR-sicheren Tauchens ist.<\/p>\n<p><a href=\"https:\/\/daivings.lv\/wp-content\/uploads\/2011\/02\/Dir_diver_02.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-107\" title=\"DIR-Taucher\" src=\"https:\/\/daivings.lv\/wp-content\/uploads\/2011\/02\/Dir_diver_02-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/daivings.lv\/wp-content\/uploads\/2011\/02\/Dir_diver_02-300x225.jpg 300w, https:\/\/daivings.lv\/wp-content\/uploads\/2011\/02\/Dir_diver_02-1024x768.jpg 1024w, https:\/\/daivings.lv\/wp-content\/uploads\/2011\/02\/Dir_diver_02-233x175.jpg 233w, https:\/\/daivings.lv\/wp-content\/uploads\/2011\/02\/Dir_diver_02.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong>Erste Regel: \u201eNicht mit dem Tauchen beginnen\u201c<\/strong><\/p>\n<p>Sie m\u00fcssen immer die Wahl haben, nicht zu tauchen. Niemand kann dich zum Tauchen zwingen, nicht einmal du selbst.<\/p>\n<p>Vielleicht haben Sie viel Geld bezahlt, um von einem Boot aus zu tauchen, aber Sie f\u00fchlen sich nicht wohl oder die Bootsbesatzung scheint nicht kompetent zu sein. Was sollte man tun? Tauchen abbrechen! Es ist nicht einfach, aber es ist die richtige Wahl. Als DIR-Fahrer kann man es schaffen \u2013 auch wenn es dumm ist und man sein Geld verliert.<\/p>\n<p>Ein weiterer wichtiger Teil des DIR-Systems ist das Teamtauchen. Du geh\u00f6rst zum Team. Ein Team besteht aus Ihnen und Ihrem Tauchpartner, vielleicht sogar aus drei Tauchern. Auf jeden Fall sind Sie und Ihr Tauchteam allein und m\u00fcssen sich auch so verhalten. Wenn Ihr Team ein Problem hat, m\u00fcssen Sie die Verantwortung f\u00fcr die L\u00f6sung dieses Problems \u00fcbernehmen. Die Sicherheit Ihres Teams darf nicht gef\u00e4hrdet werden und Sie m\u00fcssen sich mehr um Ihre Tauchpartner und deren m\u00f6gliche Probleme k\u00fcmmern als um sich selbst.<\/p>\n<p>Wenn Ihrem Tauchpartner zum Beispiel die Luft ausgeht, bedeutet das, dass Sie beide ein Problem haben. Wenn Sie beispielsweise mit Ihrem Partner in einem Raum sind und einem von Ihnen die Luft ausgeht, besteht ein hohes Risiko, dass Sie ohne Hilfe nicht rauskommen. Wenn das Problem bei Ihrem Partner auftritt, liegt es ebenfalls in Ihrer Verantwortung. Wenn Sie keine Verantwortung f\u00fcr den Luftverbrauch Ihres Partners \u00fcbernommen haben, dann haben Sie auch keine Verantwortung f\u00fcr Ihr Team \u00fcbernommen.<\/p>\n<p>Nehmen wir an, Sie tauchen in einem Team von drei Tauchern und einer von Ihnen hat leichte Probleme beim Abstieg, m\u00f6glicherweise mit dem Druckausgleich. Der Rest Ihres Teams kann nicht weiter nach unten gehen und am Boden warten oder so etwas in der Art. Sie m\u00fcssen bei Ihrem Teamtaucher bleiben und sich um den versp\u00e4teten Taucher k\u00fcmmern. Wenn er sich entschieden hat, den Lappen anzuhalten und abzuheben, muss das gesamte Kameradenteam abheben. Dies ist notwendig, da man nie wei\u00df, ob es sich um ein medizinisches Problem handelt, das beim Aufstieg zur Bewusstlosigkeit f\u00fchren und den Taucher ertr\u00e4nken k\u00f6nnte.<\/p>\n<p>Auf diese Weise tauchst du mit einem engen Team von Freunden, in dem jeder immer bereit ist, dem anderen zu helfen. Bleiben Sie mit dem 100% immer in der N\u00e4he Ihres Partners und vertrauen Sie ihm. Man muss in der N\u00e4he sein, das hei\u00dft von einem Taucher zum anderen im Abstand von maximal 3 Metern im Bild, unabh\u00e4ngig davon, wie gut die Sicht auf das Wasser ist.<\/p>\n<p>Bevor Sie jemandem helfen k\u00f6nnen, m\u00fcssen Sie sich und Ihre Ausr\u00fcstung kontrollieren. Was k\u00f6nnen Sie tun, um Ihrem Partner zu helfen, wenn Sie mit Ihren eigenen Problemen besch\u00e4ftigt sind? Diese Frage bildet die n\u00e4chste \u201eRegel\u201c.<\/p>\n<p><strong>Regel: \u201eTauche nicht mit den Zweiflern\u201c<\/strong><\/p>\n<p>\u201eZweifelhaft\u201c bedeutet einen unsicheren Taucher. Es ist jemand, dem das Team egal ist, z.B. verantwortungsloser Partner. Es kann jemand sein, der bewusst nicht auf seine Tauchausr\u00fcstung achtet und damit zeigt, dass ihm seine Sicherheit egal ist. Ein anderes Beispiel w\u00e4re ein handlungsunf\u00e4higer Taucher, der im Notfall nicht handeln k\u00f6nnte. Hier gibt es viele M\u00f6glichkeiten, denn es k\u00f6nnte sich sogar um ein unsicheres Tauchschiff oder einen inkompetenten Tauchf\u00fchrer handeln. Wenn zwei \u201eunsichere\u201c Taucher im Team ein Problem haben, dann werden Sie h\u00f6chstwahrscheinlich auch Probleme haben.<\/p>\n<p>Als DIR-Fahrer gehen Sie kein unn\u00f6tiges Risiko ein. Auf diese Weise wird das Tauchen mit einem anderen DIR-Taucher bevorzugt, oder mit einem Taucher, der die gleichen Werte f\u00fcr sicheres Tauchen teilt, aber in Bezug auf Ausbildung und Tauchausr\u00fcstung noch nicht so weit fortgeschritten ist wie Sie. Und das gilt f\u00fcr jeden, sowohl f\u00fcr die Taucher auf dem Schiff als auch f\u00fcr die Schiffsbesatzung.<\/p>\n<p>Der gr\u00f6\u00dfte Fehler ist die Aussage, dass DIR (Doing It Right) nur f\u00fcr technische Taucher gilt und nicht f\u00fcr Sporttauchen gilt. Eine solche Aussage ist ein Fehler, denn jedes Tauchen basiert auf denselben Prinzipien und dem gleichen gesunden Menschenverstand. Tauchsicherheit und gute Entspannung sind f\u00fcr jeden Taucher selbstverst\u00e4ndlich, egal, ob es sich um einen \u201eprofessionellen technischen Taucher\u201c oder einen normalen Freizeittaucher handelt. Um Risiken f\u00fcr Ihren Partner einzugehen, sollten Sie sich auf Ihrem Gebiet auskennen und sich keinen unn\u00f6tigen Risiken aussetzen.<\/p>\n<p>Die DIR-Tauchausr\u00fcstung ist standardisiert und grunds\u00e4tzlich f\u00fcr Freizeit- und \u201etechnische\u201c Taucher gleich. Die Vorteile sind vielf\u00e4ltig. Einer davon besteht darin, dass Sie Ihrem Partner bei einem Ger\u00e4teproblem problemlos helfen k\u00f6nnen, da seine Ger\u00e4te genauso funktionieren wie Ihre. Sie wissen, wo sein Ersatzregler ist, wo das Tauchmesser ist, wo alle Schl\u00e4uche hingehen, welches Ventil geschlossen werden muss usw. Sie wissen es bereits instinktiv und m\u00fcssen nicht dar\u00fcber nachdenken, was im Notfall das Leben Ihres Partners retten kann.<\/p>\n<p>Einige Taucher glauben, dass es eine spezielle Tauchmarke oder einen speziellen Tauchausr\u00fcstungshersteller gibt, der die DIR-Anforderungen ber\u00fccksichtigt. Das ist egal. Allerdings muss die Ausr\u00fcstung bestimmte Anforderungen erf\u00fcllen und schr\u00e4nkt die Auswahlm\u00f6glichkeiten ein. Ein Beispiel sind Tauchflossen.<\/p>\n<p>* Muss schwer genug sein, um die F\u00fc\u00dfe eines Trockentauchers festzuhalten (niemals Kn\u00f6chelgewichte verwenden)<\/p>\n<p>* Sie m\u00fcssen dicht sein, damit Sie in der Str\u00f6mung oder mit viel Ausr\u00fcstung schwimmen k\u00f6nnen<\/p>\n<p>* Sie sollten solide sein und keine zus\u00e4tzlichen Teile enthalten, die brechen k\u00f6nnten<\/p>\n<p>* Der G\u00fcrtel darf keine Schnellverschl\u00fcsse haben, die sich nicht schlie\u00dfen lassen<\/p>\n<p>* Kein Teil der Flossen darf dort herausragen, wo sich das Kabel oder Seil verfangen k\u00f6nnte<\/p>\n<p>* Sie sollten nicht zu lang sein, denn dann w\u00e4re es unm\u00f6glich, sie in geschlossenen R\u00e4umen zu verwenden, ohne etwas zu ber\u00fchren<\/p>\n<p>* Sie m\u00fcssen mit allen Arten von Flossen arbeiten (Flattern, Froschtritt, Babyflattern usw.)<\/p>\n<p>Daher w\u00e4ren nur die Scubapro Jetfin-Flossen oder \u00e4hnliche Nachbildungen in der Lage, diese Anforderungen zu erf\u00fcllen.<\/p>\n<p>Die andere sehr wichtige Sache ist, dass sich Ihre Tauchausr\u00fcstung und -verfahren nicht \u00e4ndern. Sie m\u00fcssen nicht alles \u00e4ndern, egal wie weit Sie gehen oder wie spezifisch das Tauchen bleibt. Die gesamte Tauchausr\u00fcstung, die Sie jetzt verwenden, k\u00f6nnen Sie auch in Zukunft verwenden. Die oben genannten Flossen eignen sich sowohl f\u00fcr Anf\u00e4ngertaucher als auch f\u00fcr WKPP-H\u00f6hlentaucher, die in Florida den Weltrekord aufgestellt haben.<\/p>\n<p>DIR-Tauchausr\u00fcstung ist so einfach wie m\u00f6glich konzipiert und weist m\u00f6glichst wenige Dinge auf, die kaputt gehen k\u00f6nnen. Die beste Tauchausr\u00fcstung ist meist teurer als normal. Zum Beispiel \u201eTechnisches Tauchen\u201c BSD. Es ist oft teurer als die R\u00fcckenplatte und der Fl\u00fcgel, die von DIR-Tauchern verwendet werden, reicht aber f\u00fcr \u201eschwierige\u201c Tauchg\u00e4nge nicht aus. Das bedeutet, dass es f\u00fcr Sie bei bestimmten Aufgaben nicht mehr funktioniert, Sie sich ein neues Ger\u00e4t kaufen und das Tauchen mit anderer Ausr\u00fcstung neu erlernen m\u00fcssen. Wenn Sie lernen, Ihre Ausr\u00fcstung zu bedienen, wissen Sie, wo sich alles befindet, bis hin zum kleinsten Knoten oder Befestigungselement. Es bedeutet auch, dass Sie wissen, wie Sie das Ger\u00e4t bedienen, ohne viel hinzusehen und nachzudenken. Dadurch wird Ihr Gehirn viel entspannter, interessanter und sicherer.<\/p>\n<p>Um ein selbstbewusster und professioneller Taucher zu werden, braucht man \u00dcbung. Sie ben\u00f6tigen folgende F\u00e4higkeiten: Luftversorgung, hervorragenden Auftrieb und die F\u00e4higkeit, Probleme unter Wasser zu l\u00f6sen. Sie m\u00fcssen wissen, wie man mit einer Rolle, einer Startboje, Dekompressionsflaschen und einem Roller umgeht.<\/p>\n<p>Sie m\u00fcssen au\u00dferdem Ihre Schwimmtechnik verbessern, wissen, wie man ohne Maske schwimmt, Ersatzlampen verwenden, die Ballonventile schlie\u00dfen usw. Wenn Sie regelm\u00e4\u00dfig Tauchen \u00fcben, bedeutet das, dass Sie Ihre F\u00e4higkeiten jederzeit aufrechterhalten.<\/p>\n<p>Es ist wichtig, dass ein Taucher in guter k\u00f6rperlicher Verfassung bleibt. Tauchausr\u00fcstung ist schwer und je st\u00e4rker der K\u00f6rper eines Tauchers ist, desto weniger Kraft muss er aufbringen, um seine Tauchausr\u00fcstung zu tragen. Wenn Sie k\u00f6rperlich stark sind, haben Sie eine bessere Chance, Stress zu \u00fcberwinden und eine kritische Situation zu \u00fcberstehen.<\/p>\n<p>Im Internet finden Sie viele Informationen zum DIR-System, zur Philosophie und zur Ausstattung, es besteht die M\u00f6glichkeit, dieses Wissen zu studieren und zu erwerben. GUE (Global Underwater Explorers) ist eine gute Ausbildungswahl, da die Ausbildung von Ausbildern durchgef\u00fchrt wird, die sich mit dem DIR-System auskennen. GUE hat ein Buch auf Englisch ver\u00f6ffentlicht, \u201eDoing It Right: The Fundamentals of Better Diving\u201c, geschrieben vom H\u00f6hlenforscher und GUE-Erfinder Jarrod Jablonski.<\/p>\n<p>Teil Eins, \u00fcbersetzt mit Genehmigung von Peter Steinhoff. Im Falle einer erneuten Ver\u00f6ffentlichung Verweis auf https:\/\/dir-diver.com und\u00a0<a href=\"https:\/\/old.daivings.lv\/\">https:\/\/www.daivings.lv<\/a><\/p>\n<p>Diskutieren <a rel=\"nofollow\" href=\"https:\/\/daivings.lv\/goto\/https:\/\/www.daivings.lv\/forum\/showthread.php?p=6635\"  >im Divings.lv-Forum<\/a>!<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Das DIR-System basiert auf der Einstellung und den Werten zum Tauchen, es ist nicht nur ein Tauchausr\u00fcstungssystem, wie viele Taucher denken. Tauchen ist ein tolles Hobby und sollte sicher durchgef\u00fchrt werden. &quot;Sicherheit&quot; bedeutet, dass der Taucher keine unn\u00f6tigen Risiken eingeht, die [...]<\/p>","protected":false},"author":1,"featured_media":107,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[20],"class_list":["post-106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-dir"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kas ir DIR (Doing It Right) sist\u0113ma - Daivings.lv<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/daivings.lv\/de\/das-ist-das-verzeichnis-das-es-richtig-macht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kas ir DIR (Doing It Right) sist\u0113ma - Daivings.lv\" \/>\n<meta property=\"og:description\" content=\"DIR sist\u0113mas pamat\u0101 ir attieksme un v\u0113rt\u012bbas pret daivingu, t\u0101 nav tikai daivinga ekip\u0113juma sist\u0113ma, k\u0101 dom\u0101 daudzi nir\u0113ji. Daivings ir lielisks hobijs un tas ir j\u0101dara dro\u0161i. Ar &#8220;dro\u0161\u012bbu&#8221; tiek dom\u0101ts tas, ka daiveris neuz\u0146emas nevajadz\u012bgus riskus, kas ir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/daivings.lv\/de\/das-ist-das-verzeichnis-das-es-richtig-macht\/\" \/>\n<meta property=\"og:site_name\" content=\"Daivings.lv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/daivings\/\" \/>\n<meta property=\"article:published_time\" content=\"2007-04-08T07:26:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-02-27T07:35:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/daivings.lv\/wp-content\/uploads\/2011\/02\/Dir_diver_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valters\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@daivings\" \/>\n<meta name=\"twitter:site\" content=\"@daivings\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valters\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/kas-ir-dir-doing-it-right-sistema\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/kas-ir-dir-doing-it-right-sistema\\\/\"},\"author\":{\"name\":\"Valters\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/person\\\/2d38bbddcd6444621ca8bcd097565438\"},\"headline\":\"Kas ir DIR (Doing It Right) sist\u0113ma\",\"datePublished\":\"2007-04-08T07:26:51+00:00\",\"dateModified\":\"2011-02-27T07:35:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/kas-ir-dir-doing-it-right-sistema\\\/\"},\"wordCount\":1723,\"publisher\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/kas-ir-dir-doing-it-right-sistema\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/Dir_diver_02.jpg\",\"keywords\":[\"DIR\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/kas-ir-dir-doing-it-right-sistema\\\/\",\"url\":\"https:\\\/\\\/daivings.lv\\\/kas-ir-dir-doing-it-right-sistema\\\/\",\"name\":\"Kas ir DIR (Doing It Right) sist\u0113ma - Daivings.lv\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/kas-ir-dir-doing-it-right-sistema\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/kas-ir-dir-doing-it-right-sistema\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/Dir_diver_02.jpg\",\"datePublished\":\"2007-04-08T07:26:51+00:00\",\"dateModified\":\"2011-02-27T07:35:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/kas-ir-dir-doing-it-right-sistema\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/daivings.lv\\\/kas-ir-dir-doing-it-right-sistema\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/kas-ir-dir-doing-it-right-sistema\\\/#primaryimage\",\"url\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/Dir_diver_02.jpg\",\"contentUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/2011\\\/02\\\/Dir_diver_02.jpg\",\"width\":\"2048\",\"height\":\"1536\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/kas-ir-dir-doing-it-right-sistema\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"S\u0101kums\",\"item\":\"https:\\\/\\\/daivings.lv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kas ir DIR (Doing It Right) sist\u0113ma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#website\",\"url\":\"https:\\\/\\\/daivings.lv\\\/\",\"name\":\"Daivings.lv\",\"description\":\"PADI kursi Latvij\u0101, Daivinga klubs pied\u0101v\u0101 nir\u0161anas kursus &amp; PADI Instruktors\",\"publisher\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/daivings.lv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#organization\",\"name\":\"Daivings.lv\",\"url\":\"https:\\\/\\\/daivings.lv\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_recolor.png\",\"contentUrl\":\"https:\\\/\\\/daivings.lv\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Logo_recolor.png\",\"width\":268,\"height\":70,\"caption\":\"Daivings.lv\"},\"image\":{\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/daivings\\\/\",\"https:\\\/\\\/x.com\\\/daivings\",\"https:\\\/\\\/instagram.com\\\/daivingslv\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/daivings.lv\\\/#\\\/schema\\\/person\\\/2d38bbddcd6444621ca8bcd097565438\",\"name\":\"Valters\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g\",\"caption\":\"Valters\"},\"description\":\"Publik\u0101cijas autors ir aizraut\u012bgs zem\u016bdens nir\u0113js, nir\u0113ju instructors - treneris un profesion\u0101ls fotogr\u0101fs, zem\u016bdens operators. Uzs\u0101cis nir\u0113ja gaitas 2005.gada 20.oktobr\u012b, izejot apm\u0101c\u012bbu Daivinga Instruktoru Profesion\u0101l\u0101 Asoci\u0101cij\u0101, DIPA (Ang. PADI \u2013 Professional Association of Diving Instructors ), tren\u0113jies nir\u0161anas profesion\u0101l\u0101s izaugsmes apm\u0101c\u012bb\u0101 Adrijas un Jonijas j\u016br\u0101s, Zieme\u013cu Atlantijas oke\u0101na sal\u0101s, Sarkan\u0101 j\u016br\u0101, Norv\u0113\u0123u j\u016br\u0101 un Vidusj\u016br\u0101. Piedal\u012bjies zem\u016bdens arheolo\u0123isk\u0101 projekt\u0101 Latvij\u0101. 2006.gada 24.j\u016blij\u0101 izveidojis nir\u0161anas klubu \u201cDaivings.lv\u201d. Paveicis vair\u0101k k\u0101 5000 ienir\u0161anas ar zem\u016bdens elpojamo apar\u0101tu. Piedal\u012bjies daudz\u0101s nir\u0161anas eksped\u012bcij\u0101s, interes\u0113jas par ekolo\u0123iju un to k\u0101 klimata izmai\u0146as ietekm\u0113 zem\u016bdens pasauli.\",\"url\":\"https:\\\/\\\/daivings.lv\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Was ist das DIR-System (Doing It Right) \u2013 Daivings.lv","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/daivings.lv\/de\/das-ist-das-verzeichnis-das-es-richtig-macht\/","og_locale":"de_DE","og_type":"article","og_title":"Kas ir DIR (Doing It Right) sist\u0113ma - Daivings.lv","og_description":"DIR sist\u0113mas pamat\u0101 ir attieksme un v\u0113rt\u012bbas pret daivingu, t\u0101 nav tikai daivinga ekip\u0113juma sist\u0113ma, k\u0101 dom\u0101 daudzi nir\u0113ji. Daivings ir lielisks hobijs un tas ir j\u0101dara dro\u0161i. Ar &#8220;dro\u0161\u012bbu&#8221; tiek dom\u0101ts tas, ka daiveris neuz\u0146emas nevajadz\u012bgus riskus, kas ir [&hellip;]","og_url":"https:\/\/daivings.lv\/de\/das-ist-das-verzeichnis-das-es-richtig-macht\/","og_site_name":"Daivings.lv","article_publisher":"https:\/\/facebook.com\/daivings\/","article_published_time":"2007-04-08T07:26:51+00:00","article_modified_time":"2011-02-27T07:35:07+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/daivings.lv\/wp-content\/uploads\/2011\/02\/Dir_diver_02.jpg","type":"image\/jpeg"}],"author":"Valters","twitter_card":"summary_large_image","twitter_creator":"@daivings","twitter_site":"@daivings","twitter_misc":{"Verfasst von":"Valters","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/daivings.lv\/kas-ir-dir-doing-it-right-sistema\/#article","isPartOf":{"@id":"https:\/\/daivings.lv\/kas-ir-dir-doing-it-right-sistema\/"},"author":{"name":"Valters","@id":"https:\/\/daivings.lv\/#\/schema\/person\/2d38bbddcd6444621ca8bcd097565438"},"headline":"Kas ir DIR (Doing It Right) sist\u0113ma","datePublished":"2007-04-08T07:26:51+00:00","dateModified":"2011-02-27T07:35:07+00:00","mainEntityOfPage":{"@id":"https:\/\/daivings.lv\/kas-ir-dir-doing-it-right-sistema\/"},"wordCount":1723,"publisher":{"@id":"https:\/\/daivings.lv\/#organization"},"image":{"@id":"https:\/\/daivings.lv\/kas-ir-dir-doing-it-right-sistema\/#primaryimage"},"thumbnailUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/2011\/02\/Dir_diver_02.jpg","keywords":["DIR"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/daivings.lv\/kas-ir-dir-doing-it-right-sistema\/","url":"https:\/\/daivings.lv\/kas-ir-dir-doing-it-right-sistema\/","name":"Was ist das DIR-System (Doing It Right) \u2013 Daivings.lv","isPartOf":{"@id":"https:\/\/daivings.lv\/#website"},"primaryImageOfPage":{"@id":"https:\/\/daivings.lv\/kas-ir-dir-doing-it-right-sistema\/#primaryimage"},"image":{"@id":"https:\/\/daivings.lv\/kas-ir-dir-doing-it-right-sistema\/#primaryimage"},"thumbnailUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/2011\/02\/Dir_diver_02.jpg","datePublished":"2007-04-08T07:26:51+00:00","dateModified":"2011-02-27T07:35:07+00:00","breadcrumb":{"@id":"https:\/\/daivings.lv\/kas-ir-dir-doing-it-right-sistema\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/daivings.lv\/kas-ir-dir-doing-it-right-sistema\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/daivings.lv\/kas-ir-dir-doing-it-right-sistema\/#primaryimage","url":"https:\/\/daivings.lv\/wp-content\/uploads\/2011\/02\/Dir_diver_02.jpg","contentUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/2011\/02\/Dir_diver_02.jpg","width":"2048","height":"1536"},{"@type":"BreadcrumbList","@id":"https:\/\/daivings.lv\/kas-ir-dir-doing-it-right-sistema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"S\u0101kums","item":"https:\/\/daivings.lv\/"},{"@type":"ListItem","position":2,"name":"Kas ir DIR (Doing It Right) sist\u0113ma"}]},{"@type":"WebSite","@id":"https:\/\/daivings.lv\/#website","url":"https:\/\/daivings.lv\/","name":"Tauchen.lv","description":"PADI-Kurse in Lettland, Tauchclub bietet Tauchkurse und PADI-Lehrer an","publisher":{"@id":"https:\/\/daivings.lv\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/daivings.lv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/daivings.lv\/#organization","name":"Tauchen.lv","url":"https:\/\/daivings.lv\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/daivings.lv\/#\/schema\/logo\/image\/","url":"https:\/\/daivings.lv\/wp-content\/uploads\/2024\/01\/Logo_recolor.png","contentUrl":"https:\/\/daivings.lv\/wp-content\/uploads\/2024\/01\/Logo_recolor.png","width":268,"height":70,"caption":"Daivings.lv"},"image":{"@id":"https:\/\/daivings.lv\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/daivings\/","https:\/\/x.com\/daivings","https:\/\/instagram.com\/daivingslv\/"]},{"@type":"Person","@id":"https:\/\/daivings.lv\/#\/schema\/person\/2d38bbddcd6444621ca8bcd097565438","name":"Walter","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45047dac47557f128c99a269e520271a2f6b93ff555d2311343e258697b9085d?s=96&d=wavatar&r=g","caption":"Valters"},"description":"Der Autor der Publikation ist ein leidenschaftlicher Unterwassertaucher, Tauchlehrer \u2013 Trainer und professioneller Fotograf, Unterwasseroperator. Begann am 20. Oktober 2005 mit dem Tauchen und absolvierte eine Ausbildung beim Berufsverband der Tauchlehrer DIPA (dt. PADI \u2013 Berufsverband der Tauchlehrer). Er absolvierte eine Berufsausbildung f\u00fcr das Tauchen in der Adria und im Ionischen Meer sowie auf den Inseln des Nordens Atlantischer Ozean, Rotes Meer, Norwegisches Meer und im Mittelmeer. Teilnahme an einem Unterwasserarch\u00e4ologieprojekt in Lettland. Am 24. Juli 2006 gr\u00fcndete er den Tauchclub \u201eDaivings.lv\u201c. Mehr als 5000 Tauchg\u00e4nge gemacht. Hat an vielen Tauchexpeditionen teilgenommen, interessiert sich f\u00fcr \u00d6kologie und wie sich der Klimawandel auf die Unterwasserwelt auswirkt.","url":"https:\/\/daivings.lv\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/posts\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/comments?post=106"}],"version-history":[{"count":0,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/posts\/106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/media\/107"}],"wp:attachment":[{"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/media?parent=106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/categories?post=106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/daivings.lv\/de\/wp-json\/wp\/v2\/tags?post=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}